{"id":20329,"date":"2025-02-03T09:37:40","date_gmt":"2025-02-03T12:37:40","guid":{"rendered":"https:\/?p=20329"},"modified":"2025-02-03T09:39:36","modified_gmt":"2025-02-03T12:39:36","slug":"mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/","title":{"rendered":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo"},"content":{"rendered":"<p>Nesse domingo (2), por volta das 19h, policiais militares do 14\u00ba BPM de Serra Talhada foram acionados para uma ocorr\u00eancia de agress\u00e3o em Triunfo.<\/p>\n<p>No local, a mulher que acionou o efetivo relatou que o imputado chego \u00e0 sua resid\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\u00e3o contra ela.<\/p>\n<p>Ainda de acordo com a v\u00edtima, o agressor puxou seus cabelos, no instante, que para se defender, ela segurou no pesco\u00e7o dele. Apesar do ocorrido, a mulher n\u00e3o apresentava les\u00f5es. O desentedimento teria sido motividado ap\u00f3s uma discuss\u00e3o entres os dois.<\/p>\n<p>Os dois foram encaminahdos \u00e0 Delegacia de Pol\u00edcia Civil para ado\u00e7\u00e3o das medidas julgadas cab\u00edveis.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesse domingo (2), por volta das 19h, policiais militares do 14\u00ba BPM de Serra Talhada foram acionados para uma ocorr\u00eancia de agress\u00e3o em Triunfo. No local, a mulher que acionou o efetivo relatou que o imputado chego \u00e0 sua resid\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\u00e3o contra ela. Ainda de acordo com a v\u00edtima, o agressor puxou seus cabelos, no instante, que para se defender, ela segurou no pesco\u00e7o dele. Apesar do ocorrido, a mulher n\u00e3o apresentava les\u00f5es. O desentedimento teria sido motividado ap\u00f3s uma discuss\u00e3o entres os dois. Os dois foram encaminahdos \u00e0 Delegacia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20330,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[151],"tags":[],"class_list":["post-20329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nesse domingo (2), por volta das 19h, policiais militares do 14\u00ba BPM de Serra Talhada foram acionados para uma ocorr\u00eancia de agress\u00e3o em Triunfo. No local, a mulher que acionou o efetivo relatou que o imputado chego \u00e0 sua resid\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\u00e3o contra ela. Ainda de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nesse domingo (2), por volta das 19h, policiais militares do 14\u00ba BPM de Serra Talhada foram acionados para uma ocorr\u00eancia de agress\u00e3o em Triunfo. No local, a mulher que acionou o efetivo relatou que o imputado chego \u00e0 sua resid\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\u00e3o contra ela. Ainda de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/transferir-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#blogposting\",\"name\":\"Mulher tem cabelo puxado e segura no pesco\\u00e7o de agressor para se defender em Triunfo - Serra FM 87,9\",\"headline\":\"Mulher tem cabelo puxado e segura no pesco\\u00e7o de agressor para se defender em Triunfo\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/transferir-1.jpg\",\"width\":276,\"height\":183},\"datePublished\":\"2025-02-03T09:37:40-03:00\",\"dateModified\":\"2025-02-03T09:39:36-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#webpage\"},\"articleSection\":\"Pol\\u00edcia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/policia\\\/#listItem\",\"name\":\"Pol\\u00edcia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/policia\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edcia\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/policia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#listItem\",\"name\":\"Mulher tem cabelo puxado e segura no pesco\\u00e7o de agressor para se defender em Triunfo\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#listItem\",\"position\":3,\"name\":\"Mulher tem cabelo puxado e segura no pesco\\u00e7o de agressor para se defender em Triunfo\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/policia\\\/#listItem\",\"name\":\"Pol\\u00edcia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/\",\"name\":\"Mulher tem cabelo puxado e segura no pesco\\u00e7o de agressor para se defender em Triunfo - Serra FM 87,9\",\"description\":\"Nesse domingo (2), por volta das 19h, policiais militares do 14\\u00ba BPM de Serra Talhada foram acionados para uma ocorr\\u00eancia de agress\\u00e3o em Triunfo. No local, a mulher que acionou o efetivo relatou que o imputado chego \\u00e0 sua resid\\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\\u00e3o contra ela. Ainda de\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/transferir-1.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#mainImage\",\"width\":276,\"height\":183},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\\\/#mainImage\"},\"datePublished\":\"2025-02-03T09:37:40-03:00\",\"dateModified\":\"2025-02-03T09:39:36-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo - Serra FM 87,9","description":"Nesse domingo (2), por volta das 19h, policiais militares do 14\u00ba BPM de Serra Talhada foram acionados para uma ocorr\u00eancia de agress\u00e3o em Triunfo. No local, a mulher que acionou o efetivo relatou que o imputado chego \u00e0 sua resid\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\u00e3o contra ela. Ainda de","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#blogposting","name":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo - Serra FM 87,9","headline":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/transferir-1.jpg","width":276,"height":183},"datePublished":"2025-02-03T09:37:40-03:00","dateModified":"2025-02-03T09:39:36-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#webpage"},"articleSection":"Pol\u00edcia"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/policia\/#listItem","name":"Pol\u00edcia"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/policia\/#listItem","position":2,"name":"Pol\u00edcia","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/policia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#listItem","name":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#listItem","position":3,"name":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/policia\/#listItem","name":"Pol\u00edcia"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/","name":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo - Serra FM 87,9","description":"Nesse domingo (2), por volta das 19h, policiais militares do 14\u00ba BPM de Serra Talhada foram acionados para uma ocorr\u00eancia de agress\u00e3o em Triunfo. No local, a mulher que acionou o efetivo relatou que o imputado chego \u00e0 sua resid\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\u00e3o contra ela. Ainda de","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/transferir-1.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#mainImage","width":276,"height":183},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/#mainImage"},"datePublished":"2025-02-03T09:37:40-03:00","dateModified":"2025-02-03T09:39:36-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo - Serra FM 87,9","twitter:description":"Nesse domingo (2), por volta das 19h, policiais militares do 14\u00ba BPM de Serra Talhada foram acionados para uma ocorr\u00eancia de agress\u00e3o em Triunfo. No local, a mulher que acionou o efetivo relatou que o imputado chego \u00e0 sua resid\u00eancia embriagdo, efetuou chutes na porta e desferiu palavaras de baixo cal\u00e3o contra ela. Ainda de","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/transferir-1.jpg"},"aioseo_meta_data":{"post_id":"20329","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 13:27:41","updated":"2026-07-21 13:27:41"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/policia\/\" title=\"Pol\u00edcia\">Pol\u00edcia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Pol\u00edcia","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/policia\/"},{"label":"Mulher tem cabelo puxado e segura no pesco\u00e7o de agressor para se defender em Triunfo","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/mulher-tem-cabelo-puxado-e-segura-no-pescoco-de-agressor-para-se-defender-em-triunfo\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/transferir-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-5hT","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=20329"}],"version-history":[{"count":2,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20329\/revisions"}],"predecessor-version":[{"id":20332,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20329\/revisions\/20332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/20330"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=20329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=20329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=20329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}