{"id":20567,"date":"2025-02-10T17:53:53","date_gmt":"2025-02-10T20:53:53","guid":{"rendered":"https:\/?p=20567"},"modified":"2025-02-10T17:53:53","modified_gmt":"2025-02-10T20:53:53","slug":"marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/","title":{"rendered":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual"},"content":{"rendered":"<p>O ex-prefeito de Flores, Marconi Santana,\u00a0 hoje no PSB, est\u00e1 ampliando as discuss\u00f5es em torno de sua pr\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real.<\/p>\n<p>Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\u00e1rios no estado. O prefeito tem ouvido tamb\u00e9m algumas lideran\u00e7as regionais. Essa semana, participa ao lado do prefeito Giba Ribeiro do encontro nacional de prefeitos em Bras\u00edlia.<\/p>\n<p>Sem considerar o j\u00e1 Deputado Luciano Duque e Sebasti\u00e3o Oliveira, com base em Serra Talhada, e que disputar\u00e3o mandados na Alepe, Marconi \u00e9 o segundo nome a discutir essa possibilidade na regi\u00e3o.<\/p>\n<p>O outro nome \u00e9 o do tamb\u00e9m socialista e ex-prefeito de Itapetim, Adelmo Moura. E a\u00ed reside a quest\u00e3o: Santana tem sinalizado que, dada a articula\u00e7\u00e3o de Jo\u00e3o Campos em torno do nome do Alto Paje\u00fa, pode discutir a migra\u00e7\u00e3o para uma outra legenda, com a sinaliza\u00e7\u00e3o de disputar com chances reais o mandato. Publicamente, o ex-prefeito ainda n\u00e3o falou dessa possibilidade, mas \u00e9 certo dizer que em breve deve montar uma agenda a partir da regi\u00e3o para discutir seu futuro.<\/p>\n<p>Em suas apari\u00e7\u00f5es p\u00fablicas, o ex-prefeito tem levantado bandeiras regionais.\u00a0\u201cO Paje\u00fa tem ficado um pouco atr\u00e1s. Se n\u00e3o fossem os prefeitos dos Paje\u00fa, estar\u00edamos mal. E aqui temos os\u00a0melhores quadros de prefeitos, n\u00e3o sei o que seria sem eles\u201d, disse em encontro com a imprensa.<\/p>\n<p>Reclamou do subfinanciamento pra sa\u00fade e da prioridade que os polos onde ficam unidades regionais tem. \u201cO maior calo \u00e9 a sa\u00fade p\u00fablica. Hoje a regi\u00e3o s\u00f3 conta com os hospitais Em\u00edlia C\u00e2mara, Eduardo Campos e Hospam. S\u00f3 Flores e Carna\u00edba tem unidades municipais. Assim, cidades como Serra e Afogados absorvem todo o atendimento. N\u00e3o tem vaga pras outras cidades. Isso faz com que os outros munic\u00edpios n\u00e3o tenham o mesmo espa\u00e7o.\u00a0Estamos nessa luta com a governadora para ampliar o atendimento. S\u00f3 em Flores, aportamos quase R$ 700 mil, R$ 800 mil m\u00eas\u201d.<\/p>\n<p>Com informa\u00e7\u00f5es do Blog Nill j\u00fanior<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-prefeito de Flores, Marconi Santana,\u00a0 hoje no PSB, est\u00e1 ampliando as discuss\u00f5es em torno de sua pr\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real. Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\u00e1rios no estado. O prefeito tem ouvido tamb\u00e9m algumas lideran\u00e7as regionais. Essa semana, participa ao lado do prefeito Giba Ribeiro do encontro nacional de prefeitos em Bras\u00edlia. Sem considerar o j\u00e1 Deputado Luciano Duque e Sebasti\u00e3o Oliveira, com base em Serra Talhada, e que disputar\u00e3o mandados na Alepe, Marconi \u00e9 o segundo nome a discutir essa possibilidade na regi\u00e3o. O outro nome [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[144],"tags":[],"class_list":["post-20567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O ex-prefeito de Flores, Marconi Santana, hoje no PSB, est\u00e1 ampliando as discuss\u00f5es em torno de sua pr\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real. Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\u00e1rios no estado. O prefeito tem ouvido tamb\u00e9m algumas lideran\u00e7as regionais. Essa semana, participa ao lado do\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O ex-prefeito de Flores, Marconi Santana, hoje no PSB, est\u00e1 ampliando as discuss\u00f5es em torno de sua pr\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real. Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\u00e1rios no estado. O prefeito tem ouvido tamb\u00e9m algumas lideran\u00e7as regionais. Essa semana, participa ao lado do\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/01\/thumbnail_marconi-assina.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#blogposting\",\"name\":\"Marconi Santana amplia discuss\\u00e3o sobre possibilidade de candidatura a Estadual - Serra FM 87,9\",\"headline\":\"Marconi Santana amplia discuss\\u00e3o sobre possibilidade de candidatura a Estadual\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/thumbnail_marconi-assina.jpg\",\"width\":600,\"height\":400},\"datePublished\":\"2025-02-10T17:53:53-03:00\",\"dateModified\":\"2025-02-10T17:53:53-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#webpage\"},\"articleSection\":\"Pol\\u00edtica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#listItem\",\"name\":\"Marconi Santana amplia discuss\\u00e3o sobre possibilidade de candidatura a Estadual\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#listItem\",\"position\":3,\"name\":\"Marconi Santana amplia discuss\\u00e3o sobre possibilidade de candidatura a Estadual\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/\",\"name\":\"Marconi Santana amplia discuss\\u00e3o sobre possibilidade de candidatura a Estadual - Serra FM 87,9\",\"description\":\"O ex-prefeito de Flores, Marconi Santana, hoje no PSB, est\\u00e1 ampliando as discuss\\u00f5es em torno de sua pr\\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real. Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\\u00e1rios no estado. O prefeito tem ouvido tamb\\u00e9m algumas lideran\\u00e7as regionais. Essa semana, participa ao lado do\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/thumbnail_marconi-assina.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#mainImage\",\"width\":600,\"height\":400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\\\/#mainImage\"},\"datePublished\":\"2025-02-10T17:53:53-03:00\",\"dateModified\":\"2025-02-10T17:53:53-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual - Serra FM 87,9","description":"O ex-prefeito de Flores, Marconi Santana, hoje no PSB, est\u00e1 ampliando as discuss\u00f5es em torno de sua pr\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real. Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\u00e1rios no estado. O prefeito tem ouvido tamb\u00e9m algumas lideran\u00e7as regionais. Essa semana, participa ao lado do","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#blogposting","name":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual - Serra FM 87,9","headline":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/01\/thumbnail_marconi-assina.jpg","width":600,"height":400},"datePublished":"2025-02-10T17:53:53-03:00","dateModified":"2025-02-10T17:53:53-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#webpage"},"articleSection":"Pol\u00edtica"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","name":"Pol\u00edtica"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","position":2,"name":"Pol\u00edtica","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#listItem","name":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#listItem","position":3,"name":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","name":"Pol\u00edtica"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/","name":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual - Serra FM 87,9","description":"O ex-prefeito de Flores, Marconi Santana, hoje no PSB, est\u00e1 ampliando as discuss\u00f5es em torno de sua pr\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real. Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\u00e1rios no estado. O prefeito tem ouvido tamb\u00e9m algumas lideran\u00e7as regionais. Essa semana, participa ao lado do","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/01\/thumbnail_marconi-assina.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#mainImage","width":600,"height":400},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/#mainImage"},"datePublished":"2025-02-10T17:53:53-03:00","dateModified":"2025-02-10T17:53:53-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual - Serra FM 87,9","twitter:description":"O ex-prefeito de Flores, Marconi Santana, hoje no PSB, est\u00e1 ampliando as discuss\u00f5es em torno de sua pr\u00e9-candidatura a Deputado Estadual e tem avaliado essa possibilidade como real. Semana passada, Santana esteve conversando com jornalistas e debatendo os cen\u00e1rios no estado. O prefeito tem ouvido tamb\u00e9m algumas lideran\u00e7as regionais. Essa semana, participa ao lado do","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/01\/thumbnail_marconi-assina.jpg"},"aioseo_meta_data":{"post_id":"20567","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 13:36:03","updated":"2026-07-21 13:36:03"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/\" title=\"Pol\u00edtica\">Pol\u00edtica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMarconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Pol\u00edtica","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/"},{"label":"Marconi Santana amplia discuss\u00e3o sobre possibilidade de candidatura a Estadual","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/marconi-santana-amplia-discussao-sobre-possibilidade-de-candidatura-a-estadual\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/01\/thumbnail_marconi-assina.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-5lJ","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=20567"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20567\/revisions"}],"predecessor-version":[{"id":20568,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20567\/revisions\/20568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/2188"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=20567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=20567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=20567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}