{"id":20711,"date":"2025-02-14T19:14:46","date_gmt":"2025-02-14T22:14:46","guid":{"rendered":"https:\/?p=20711"},"modified":"2025-02-14T19:14:46","modified_gmt":"2025-02-14T22:14:46","slug":"datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/","title":{"rendered":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos"},"content":{"rendered":"<p>Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista.<\/p>\n<p>A reprova\u00e7\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\u00famero que agora \u00e9 de 32%.<\/p>\n<p>A \u00faltima pesquisa havia sido realizada no m\u00eas de dezembro. Agora, o instituto ouviu 2.007 eleitores em 113 cidades brasileiras, entre a segunda (10) e a ter\u00e7a-feira (11). O levantamento tem uma margem de erro de dois pontos para mais ou para menos.<\/p>\n<p>A pesquisa divulgada nesta sexta foi a primeira realizada ap\u00f3s a\u00a0\u201ccrise do Pix\u201d, ocorrida em janeiro, com a not\u00edcia de que o governo passaria a fiscalizar transa\u00e7\u00f5es superiores a R$ 5.000 pelo sistema de pagamentos. A rea\u00e7\u00e3o da oposi\u00e7\u00e3o, que sugeriu que poderia haver um controle indevido e at\u00e9 a taxa\u00e7\u00e3o do Pix, fez o governo revogar a medida.<\/p>\n<p>Nas semanas seguintes, o governo trocou o comando da Secretaria de Comunica\u00e7\u00e3o (Secom), com a\u00a0entrada de<a href=\"https:\/\/www.infomoney.com.br\/politica\/lula-bate-o-martelo-e-decide-trocar-pimenta-por-sidonio-palmeira-no-comando-da-secom\/\">\u00a0<\/a>Sid\u00f4nio Palmeira no lugar de Paulo Pimenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista. A reprova\u00e7\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\u00famero que agora \u00e9 de 32%. A \u00faltima pesquisa havia sido realizada no m\u00eas de dezembro. Agora, o instituto ouviu 2.007 eleitores em 113 cidades brasileiras, entre a segunda (10) e a ter\u00e7a-feira (11). O levantamento tem uma margem de erro de dois pontos para mais ou para menos. A pesquisa divulgada nesta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[144],"tags":[],"class_list":["post-20711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista. A reprova\u00e7\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\u00famero que agora \u00e9 de 32%. A \u00faltima\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista. A reprova\u00e7\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\u00famero que agora \u00e9 de 32%. A \u00faltima\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-8.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#blogposting\",\"name\":\"Datafolha: aprova\\u00e7\\u00e3o de Lula despenca para 24% e \\u00e9 a pior de todos os seus mandatos - Serra FM 87,9\",\"headline\":\"Datafolha: aprova\\u00e7\\u00e3o de Lula despenca para 24% e \\u00e9 a pior de todos os seus mandatos\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/download-8.jpg\",\"width\":276,\"height\":183},\"datePublished\":\"2025-02-14T19:14:46-03:00\",\"dateModified\":\"2025-02-14T19:14:46-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#webpage\"},\"articleSection\":\"Pol\\u00edtica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#listItem\",\"name\":\"Datafolha: aprova\\u00e7\\u00e3o de Lula despenca para 24% e \\u00e9 a pior de todos os seus mandatos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#listItem\",\"position\":3,\"name\":\"Datafolha: aprova\\u00e7\\u00e3o de Lula despenca para 24% e \\u00e9 a pior de todos os seus mandatos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/\",\"name\":\"Datafolha: aprova\\u00e7\\u00e3o de Lula despenca para 24% e \\u00e9 a pior de todos os seus mandatos - Serra FM 87,9\",\"description\":\"Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\\u00e7\\u00e3o do presidente Luiz In\\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista. A reprova\\u00e7\\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\\u00famero que agora \\u00e9 de 32%. A \\u00faltima\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/download-8.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#mainImage\",\"width\":276,\"height\":183},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\\\/#mainImage\"},\"datePublished\":\"2025-02-14T19:14:46-03:00\",\"dateModified\":\"2025-02-14T19:14:46-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos - Serra FM 87,9","description":"Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista. A reprova\u00e7\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\u00famero que agora \u00e9 de 32%. A \u00faltima","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#blogposting","name":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos - Serra FM 87,9","headline":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-8.jpg","width":276,"height":183},"datePublished":"2025-02-14T19:14:46-03:00","dateModified":"2025-02-14T19:14:46-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#webpage"},"articleSection":"Pol\u00edtica"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","name":"Pol\u00edtica"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","position":2,"name":"Pol\u00edtica","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#listItem","name":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#listItem","position":3,"name":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","name":"Pol\u00edtica"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/","name":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos - Serra FM 87,9","description":"Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista. A reprova\u00e7\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\u00famero que agora \u00e9 de 32%. A \u00faltima","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-8.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#mainImage","width":276,"height":183},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/#mainImage"},"datePublished":"2025-02-14T19:14:46-03:00","dateModified":"2025-02-14T19:14:46-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos - Serra FM 87,9","twitter:description":"Uma pesquisa do instituto Datafolha divulgada nesta sexta-feira (14), mostra que a aprova\u00e7\u00e3o do presidente Luiz In\u00e1cio Lula da Silva (PT) caiu de 35% para 24%, recorde negativa entre todos os mandatos do petista. A reprova\u00e7\u00e3o passou de 34% para 41%. Antes, 29% achavam o governo regular, n\u00famero que agora \u00e9 de 32%. A \u00faltima","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-8.jpg"},"aioseo_meta_data":{"post_id":"20711","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 13:46:47","updated":"2026-07-21 13:46:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/\" title=\"Pol\u00edtica\">Pol\u00edtica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDatafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Pol\u00edtica","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/"},{"label":"Datafolha: aprova\u00e7\u00e3o de Lula despenca para 24% e \u00e9 a pior de todos os seus mandatos","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/datafolha-aprovacao-de-lula-despenca-para-24-e-e-a-pior-de-todos-os-seus-mandatos\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-8.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-5o3","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=20711"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20711\/revisions"}],"predecessor-version":[{"id":20713,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20711\/revisions\/20713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/20712"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=20711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=20711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=20711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}