{"id":20720,"date":"2025-02-16T10:13:38","date_gmt":"2025-02-16T13:13:38","guid":{"rendered":"https:\/?p=20720"},"modified":"2025-02-16T10:13:38","modified_gmt":"2025-02-16T13:13:38","slug":"em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/","title":{"rendered":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro"},"content":{"rendered":"<p>Tabu quebrado e vit\u00f3ria com autoridade. O\u00a0<strong>N\u00e1utico superou o Sport por 2&#215;1 neste s\u00e1bado<\/strong>\u00a0(15), na Ilha do Retiro, pela oitava rodada do\u00a0<strong>Campeonato Pernambucano.\u00a0<\/strong>Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\u00e7alo Paci\u00eancia descontou para o Le\u00e3o nos minutos finais.<\/p>\n<p>Al\u00e9m da vit\u00f3ria significativa,\u00a0o resultado encerrou um\u00a0<strong>jejum de seis anos sem vit\u00f3rias do Timbu sobre o rival na Ilha do Retiro.<\/strong>\u00a0Com o triunfo, o N\u00e1utico chegou a 16 pontos, assumiu a vice-lideran\u00e7a do Estadual e, temporariamente, garantiu vaga na semifinal. O Sport, por sua vez, permaneceu com 12 pontos, ocupando a quarta coloca\u00e7\u00e3o.<\/p>\n<p><strong>O jogo<\/strong><\/p>\n<p>Os primeiros minutos da partida foram de pouca criatividade para ambos os lados. O N\u00e1utico apostou na marca\u00e7\u00e3o para conter o \u00edmpeto do Sport, escalando quatro volantes entre os titulares. J\u00e1 a defesa rubro-negra cumpriu bem seu papel, evitando o primeiro ataque alvirrubro aos seis minutos, quando Igor Fernandes cruzou pela esquerda.<\/p>\n<p>A primeira finaliza\u00e7\u00e3o do jogo veio ap\u00f3s uma tabela entre Wenderson e Patrick Allan, que chutou para fora. A estrat\u00e9gia da equipe do N\u00e1utico surtiu efeito aos 15 minutos, quando o time aproveitou um erro do Sport para balan\u00e7ar as redes no Cl\u00e1ssico dos Cl\u00e1ssicos.<\/p>\n<p>Otusanya desarmou Ant\u00f4nio Carlos, e a bola sobrou para Patrick Allan, que devolveu para o atacante nigeriano finalizar e abrir o placar na Ilha do Retiro.<\/p>\n<p>Nove minutos depois, o Sport teve a chance de empatar em um chute de fora da \u00e1rea do meia Hyoran, mas o goleiro alvirrubro brilhou com uma grande defesa.<\/p>\n<p>Atr\u00e1s no placar, o Sport adotou uma postura mais ofensiva, passou a ter mais posse de bola e pressionou o N\u00e1utico. O Le\u00e3o criou boas oportunidades, incluindo uma cobran\u00e7a de falta de Barletta e tr\u00eas finaliza\u00e7\u00f5es &#8211; uma de Lenny Lobato, para fora, e duas de Carlos Alberto, que pararam na defesa.<\/p>\n<p>O Timbu tamb\u00e9m teve oportunidade de ampliar o placar com Patrick Allan de cabe\u00e7a, mas a bola parou nas m\u00e3os do goleiro rubro-negro. Sem conseguir balan\u00e7ar as redes, o time da casa foi para o intervalo em desvantagem, sob vaias da torcida rubro-negra.<\/p>\n<p><strong>Segundo tempo<\/strong><\/p>\n<p>A etapa complementar come\u00e7ou em ritmo acelerado e, com menos de um minuto, o Sport chegou a balan\u00e7ar as redes, mas o gol foi anulado por impedimento.<\/p>\n<p>Aos nove minutos, a partida foi interrompida devido a uma queda na ilumina\u00e7\u00e3o da Ilha do Retiro. O jogo foi retomado sete minutos depois, com o Sport intensificando a press\u00e3o. Aos 21, o zagueiro Chico arriscou de fora da \u00e1rea, mas mandou para fora. No minuto seguinte, Paci\u00eancia cabeceou nas m\u00e3os do goleiro alvirrubro, desperdi\u00e7ando mais uma boa oportunidade para o Le\u00e3o.<\/p>\n<p>O Sport seguiu em busca do empate e quase marcou ap\u00f3s uma cobran\u00e7a de escanteio, mas Ant\u00f4nio Carlos finalizou por cima do gol.<\/p>\n<p>O camisa 7 do Sport foi bastante acionado no segundo tempo e protagonizou a melhor chance da etapa final. Paci\u00eancia cabeceou com for\u00e7a dentro da pequena \u00e1rea, obrigando Muriel a fazer uma grande defesa.<\/p>\n<p>Nos minutos finais, o jogo ganhou intensidade e fez jus ao nome \u201cCl\u00e1ssico dos Cl\u00e1ssicos\u201d. Aos 48, o volante Igor Pereira roubou a bola no campo de defesa, avan\u00e7ou pelo gramado da Ilha do Retiro e, ao entrar na \u00e1rea, finalizou com uma cavadinha por cima do goleiro rubro-negro, ampliando a vantagem alvirrubra.<\/p>\n<p>Seis minutos depois, o atacante Paci\u00eancia descontou para o Sport, aumentando a tens\u00e3o na partida. No entanto, a press\u00e3o do Le\u00e3o n\u00e3o foi suficiente para evitar a vit\u00f3ria do N\u00e1utico, que triunfou com autoridade e assumiu a vice-lideran\u00e7a do Pernambucano.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Folha PE<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tabu quebrado e vit\u00f3ria com autoridade. O\u00a0N\u00e1utico superou o Sport por 2&#215;1 neste s\u00e1bado\u00a0(15), na Ilha do Retiro, pela oitava rodada do\u00a0Campeonato Pernambucano.\u00a0Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\u00e7alo Paci\u00eancia descontou para o Le\u00e3o nos minutos finais. Al\u00e9m da vit\u00f3ria significativa,\u00a0o resultado encerrou um\u00a0jejum de seis anos sem vit\u00f3rias do Timbu sobre o rival na Ilha do Retiro.\u00a0Com o triunfo, o N\u00e1utico chegou a 16 pontos, assumiu a vice-lideran\u00e7a do Estadual e, temporariamente, garantiu vaga na semifinal. O Sport, por sua vez, permaneceu com 12 pontos, ocupando a quarta coloca\u00e7\u00e3o. O jogo Os primeiros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-20720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tabu quebrado e vit\u00f3ria com autoridade. O N\u00e1utico superou o Sport por 2x1 neste s\u00e1bado (15), na Ilha do Retiro, pela oitava rodada do Campeonato Pernambucano. Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\u00e7alo Paci\u00eancia descontou para o Le\u00e3o nos minutos finais. Al\u00e9m da vit\u00f3ria significativa, o resultado encerrou um jejum de seis anos sem vit\u00f3rias\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tabu quebrado e vit\u00f3ria com autoridade. O N\u00e1utico superou o Sport por 2x1 neste s\u00e1bado (15), na Ilha do Retiro, pela oitava rodada do Campeonato Pernambucano. Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\u00e7alo Paci\u00eancia descontou para o Le\u00e3o nos minutos finais. Al\u00e9m da vit\u00f3ria significativa, o resultado encerrou um jejum de seis anos sem vit\u00f3rias\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-9.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#blogposting\",\"name\":\"Em jogo pegado, N\\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro - Serra FM 87,9\",\"headline\":\"Em jogo pegado, N\\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/download-9.jpg\",\"width\":275,\"height\":183},\"datePublished\":\"2025-02-16T10:13:38-03:00\",\"dateModified\":\"2025-02-16T10:13:38-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#webpage\"},\"articleSection\":\"Uncategorized\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#listItem\",\"name\":\"Em jogo pegado, N\\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#listItem\",\"position\":3,\"name\":\"Em jogo pegado, N\\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/\",\"name\":\"Em jogo pegado, N\\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro - Serra FM 87,9\",\"description\":\"Tabu quebrado e vit\\u00f3ria com autoridade. O N\\u00e1utico superou o Sport por 2x1 neste s\\u00e1bado (15), na Ilha do Retiro, pela oitava rodada do Campeonato Pernambucano. Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\\u00e7alo Paci\\u00eancia descontou para o Le\\u00e3o nos minutos finais. Al\\u00e9m da vit\\u00f3ria significativa, o resultado encerrou um jejum de seis anos sem vit\\u00f3rias\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/download-9.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#mainImage\",\"width\":275,\"height\":183},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/02\\\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\\\/#mainImage\"},\"datePublished\":\"2025-02-16T10:13:38-03:00\",\"dateModified\":\"2025-02-16T10:13:38-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro - Serra FM 87,9","description":"Tabu quebrado e vit\u00f3ria com autoridade. O N\u00e1utico superou o Sport por 2x1 neste s\u00e1bado (15), na Ilha do Retiro, pela oitava rodada do Campeonato Pernambucano. Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\u00e7alo Paci\u00eancia descontou para o Le\u00e3o nos minutos finais. Al\u00e9m da vit\u00f3ria significativa, o resultado encerrou um jejum de seis anos sem vit\u00f3rias","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#blogposting","name":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro - Serra FM 87,9","headline":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-9.jpg","width":275,"height":183},"datePublished":"2025-02-16T10:13:38-03:00","dateModified":"2025-02-16T10:13:38-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#webpage"},"articleSection":"Uncategorized"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#listItem","name":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#listItem","position":3,"name":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/","name":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro - Serra FM 87,9","description":"Tabu quebrado e vit\u00f3ria com autoridade. O N\u00e1utico superou o Sport por 2x1 neste s\u00e1bado (15), na Ilha do Retiro, pela oitava rodada do Campeonato Pernambucano. Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\u00e7alo Paci\u00eancia descontou para o Le\u00e3o nos minutos finais. Al\u00e9m da vit\u00f3ria significativa, o resultado encerrou um jejum de seis anos sem vit\u00f3rias","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-9.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#mainImage","width":275,"height":183},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/#mainImage"},"datePublished":"2025-02-16T10:13:38-03:00","dateModified":"2025-02-16T10:13:38-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro - Serra FM 87,9","twitter:description":"Tabu quebrado e vit\u00f3ria com autoridade. O N\u00e1utico superou o Sport por 2x1 neste s\u00e1bado (15), na Ilha do Retiro, pela oitava rodada do Campeonato Pernambucano. Os gols alvirrubros foram marcados por Samuel Otusanya e Igor Pereira, enquanto Gon\u00e7alo Paci\u00eancia descontou para o Le\u00e3o nos minutos finais. Al\u00e9m da vit\u00f3ria significativa, o resultado encerrou um jejum de seis anos sem vit\u00f3rias","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-9.jpg"},"aioseo_meta_data":{"post_id":"20720","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 13:46:47","updated":"2026-07-21 13:46:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEm jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Uncategorized","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/uncategorized\/"},{"label":"Em jogo pegado, N\u00e1utico vence Sport e quebra tabu de seis anos sem vencer na Ilha do Retiro","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/02\/em-jogo-pegado-nautico-vence-sport-e-quebra-tabu-de-seis-anos-sem-vencer-na-ilha-do-retiro\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/02\/download-9.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-5oc","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=20720"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20720\/revisions"}],"predecessor-version":[{"id":20722,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/20720\/revisions\/20722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/20721"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=20720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=20720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=20720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}