{"id":23113,"date":"2025-07-02T12:02:20","date_gmt":"2025-07-02T15:02:20","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23113"},"modified":"2025-07-02T12:02:20","modified_gmt":"2025-07-02T15:02:20","slug":"dupla-de-moto-amedronta-motociclistas-na-pe-320","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/","title":{"rendered":"Dupla de moto amedronta motociclistas na PE 320"},"content":{"rendered":"<p>Na noite da ter\u00e7a-feira, 1\u00b0 de julho, motociclistas entraram em contato com a Reda\u00e7\u00e3o do Blog do Cau\u00ea Rodrigues, alertando sobre uma dupla com a\u00e7\u00f5es suspeitas na rodovia Estadual PE 320, nas proximidades do s\u00edtio Capim Grosso, cerca de 3 Km do centro de Carna\u00edba.<\/p>\n<p>A dupla era desconhecida e em uma das a\u00e7\u00f5es amea\u00e7aram atacar um motociclista Carna\u00edbano com o garupa que seguia sentido Carna\u00edba, que acelerou para n\u00e3o serem abordados pela dupla suspeita que desistiu da a\u00e7\u00e3o ap\u00f3s outro motociclista seguir logo atr\u00e1s.<\/p>\n<p>Alguns trechos da referida rodovia \u00e9 alvo de assaltantes de motos como o trevo de acesso a Quixaba, trevo do povoado da It\u00e3, acesso de entrada da Matolotagem, j\u00e1 na zona rural de Flores, al\u00e9m da extens\u00e3o de acesso a Tabira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite da ter\u00e7a-feira, 1\u00b0 de julho, motociclistas entraram em contato com a Reda\u00e7\u00e3o do Blog do Cau\u00ea Rodrigues, alertando sobre uma dupla com a\u00e7\u00f5es suspeitas na rodovia Estadual PE 320, nas proximidades do s\u00edtio Capim Grosso, cerca de 3 Km do centro de Carna\u00edba. A dupla era desconhecida e em uma das a\u00e7\u00f5es amea\u00e7aram atacar um motociclista Carna\u00edbano com o garupa que seguia sentido Carna\u00edba, que acelerou para n\u00e3o serem abordados pela dupla suspeita que desistiu da a\u00e7\u00e3o ap\u00f3s outro motociclista seguir logo atr\u00e1s. Alguns trechos da referida rodovia \u00e9 alvo de assaltantes de motos como o trevo de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dupla de moto amedronta motociclistas na PE 320 - Serra FM 87,9<\/title>\n<meta name=\"description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dupla de moto amedronta motociclistas na PE 320 - Serra FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/\" \/>\n<meta property=\"og:site_name\" content=\"Serra FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T15:02:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"728\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"serrafm87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"serrafm87\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/\",\"name\":\"Dupla de moto amedronta motociclistas na PE 320 - Serra FM 87,9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sirene-noturna43-policia-728x405-1.jpg\",\"datePublished\":\"2025-07-02T15:02:20+00:00\",\"description\":\"Serra FM - Todo Mundo Ouve!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sirene-noturna43-policia-728x405-1.jpg\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sirene-noturna43-policia-728x405-1.jpg\",\"width\":728,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/dupla-de-moto-amedronta-motociclistas-na-pe-320\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dupla de moto amedronta motociclistas na PE 320\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"R\u00e1dio Serra FM 87,9\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"width\":225,\"height\":225,\"caption\":\"R\u00e1dio Serra FM 87,9\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dupla de moto amedronta motociclistas na PE 320 - Serra FM 87,9","description":"Serra FM - Todo Mundo Ouve!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/","og_locale":"pt_BR","og_type":"article","og_title":"Dupla de moto amedronta motociclistas na PE 320 - Serra FM 87,9","og_description":"Serra FM - Todo Mundo Ouve!","og_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/","og_site_name":"Serra FM 87,9","article_published_time":"2025-07-02T15:02:20+00:00","og_image":[{"width":728,"height":405,"url":"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","type":"image\/jpeg"}],"author":"serrafm87","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"serrafm87","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/","name":"Dupla de moto amedronta motociclistas na PE 320 - Serra FM 87,9","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/#primaryimage"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/#primaryimage"},"thumbnailUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","datePublished":"2025-07-02T15:02:20+00:00","description":"Serra FM - Todo Mundo Ouve!","breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/#primaryimage","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","width":728,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/dupla-de-moto-amedronta-motociclistas-na-pe-320\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"ListItem","position":2,"name":"Dupla de moto amedronta motociclistas na PE 320"}]},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serrafm879.com.br\/serrafm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"R\u00e1dio Serra FM 87,9","url":"https:\/\/serrafm879.com.br\/serrafm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","width":225,"height":225,"caption":"R\u00e1dio Serra FM 87,9"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-60N","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23113"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23113\/revisions"}],"predecessor-version":[{"id":23114,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23113\/revisions\/23114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/4096"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}