{"id":23361,"date":"2025-07-17T08:49:33","date_gmt":"2025-07-17T11:49:33","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23361"},"modified":"2025-07-17T08:49:33","modified_gmt":"2025-07-17T11:49:33","slug":"prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/","title":{"rendered":"Prefeitura de ST convoca 200 classificados para o Vanete Almeida"},"content":{"rendered":"<p>A Prefeitura de Serra Talhada, por meio da Secretaria de Assist\u00eancia Social e Cidadania, est\u00e1 convocando os 200 classificados no Sistema Habitacional Municipal para apresentar a documenta\u00e7\u00e3o exigida referente ao Cadastro de Reserva do Residencial Vanete Almeida.<\/p>\n<p>A entrega dos documentos dever\u00e1 ser feita entre os dias 17 e 24 de julho, na sede da Secretaria de Assist\u00eancia Social, localizada na Rua Manoel Pereira da Silva, n\u00ba 1059, Bairro Nossa Senhora da Penha.<\/p>\n<p>O atendimento ser\u00e1 realizado no hor\u00e1rio das 8h \u00e0s 14h.<\/p>\n<h5>PRAZO INADI\u00c1VEL<\/h5>\n<p>A convoca\u00e7\u00e3o \u00e9 exclusiva para os candidatos previamente classificados no processo de sele\u00e7\u00e3o. A Prefeitura alerta que quem n\u00e3o comparecer no prazo determinado poder\u00e1 ser exclu\u00eddo do cadastro, perdendo o direito \u00e0 continuidade no processo de sele\u00e7\u00e3o habitacional.<\/p>\n<p>Para efetivar a participa\u00e7\u00e3o no cadastro de reserva, os convocados dever\u00e3o apresentar a seguinte documenta\u00e7\u00e3o \u2013\u00a0 Documentos exigidos<strong>\u00a0(duas c\u00f3pias de cada)<\/strong>:<\/p>\n<ul>\n<li>RG e CPF;<\/li>\n<li>Comprovante de resid\u00eancia atualizado;<\/li>\n<li>Certid\u00e3o de nascimento, casamento ou de \u00f3bito do c\u00f4njuge (conforme o caso);<\/li>\n<li>N\u00famero de Identifica\u00e7\u00e3o Social (NIS) com Cad\u00danico atualizado;<\/li>\n<li>Declara\u00e7\u00e3o de uni\u00e3o est\u00e1vel (se aplic\u00e1vel);<\/li>\n<li>Atestado m\u00e9dico com CID para pessoas com defici\u00eancia;<\/li>\n<li>Comprovante de recebimento do Benef\u00edcio de Presta\u00e7\u00e3o Continuada (BPC), caso exista.<\/li>\n<\/ul>\n<p>A Secretaria refor\u00e7a que \u00e9 necess\u00e1rio levar duas c\u00f3pias de cada documento para agilizar o atendimento e garantir a organiza\u00e7\u00e3o do processo.<\/p>\n<h5>Informa\u00e7\u00f5es adicionais<\/h5>\n<p>D\u00favidas podem ser esclarecidas diretamente na sede da Secretaria de Assist\u00eancia Social. A convoca\u00e7\u00e3o faz parte da pol\u00edtica de habita\u00e7\u00e3o do munic\u00edpio, que busca garantir o direito \u00e0 moradia com transpar\u00eancia e responsabilidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Serra Talhada, por meio da Secretaria de Assist\u00eancia Social e Cidadania, est\u00e1 convocando os 200 classificados no Sistema Habitacional Municipal para apresentar a documenta\u00e7\u00e3o exigida referente ao Cadastro de Reserva do Residencial Vanete Almeida. A entrega dos documentos dever\u00e1 ser feita entre os dias 17 e 24 de julho, na sede da Secretaria de Assist\u00eancia Social, localizada na Rua Manoel Pereira da Silva, n\u00ba 1059, Bairro Nossa Senhora da Penha. O atendimento ser\u00e1 realizado no hor\u00e1rio das 8h \u00e0s 14h. PRAZO INADI\u00c1VEL A convoca\u00e7\u00e3o \u00e9 exclusiva para os candidatos previamente classificados no processo de sele\u00e7\u00e3o. A Prefeitura [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitura de ST convoca 200 classificados para o Vanete Almeida - Serra FM 87,9<\/title>\n<meta name=\"description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura de ST convoca 200 classificados para o Vanete Almeida - Serra FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/\" \/>\n<meta property=\"og:site_name\" content=\"Serra FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-17T11:49:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2021\/02\/vanetealmeida-300x169-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"serrafm87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"serrafm87\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/\",\"name\":\"Prefeitura de ST convoca 200 classificados para o Vanete Almeida - Serra FM 87,9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/vanetealmeida-300x169-1.png\",\"datePublished\":\"2025-07-17T11:49:33+00:00\",\"description\":\"Serra FM - Todo Mundo Ouve!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/vanetealmeida-300x169-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/vanetealmeida-300x169-1.png\",\"width\":300,\"height\":169},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura de ST convoca 200 classificados para o Vanete Almeida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"R\u00e1dio Serra FM 87,9\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"width\":225,\"height\":225,\"caption\":\"R\u00e1dio Serra FM 87,9\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura de ST convoca 200 classificados para o Vanete Almeida - Serra FM 87,9","description":"Serra FM - Todo Mundo Ouve!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura de ST convoca 200 classificados para o Vanete Almeida - Serra FM 87,9","og_description":"Serra FM - Todo Mundo Ouve!","og_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/","og_site_name":"Serra FM 87,9","article_published_time":"2025-07-17T11:49:33+00:00","og_image":[{"width":300,"height":169,"url":"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2021\/02\/vanetealmeida-300x169-1.png","type":"image\/png"}],"author":"serrafm87","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"serrafm87","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/","name":"Prefeitura de ST convoca 200 classificados para o Vanete Almeida - Serra FM 87,9","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/#primaryimage"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/#primaryimage"},"thumbnailUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2021\/02\/vanetealmeida-300x169-1.png","datePublished":"2025-07-17T11:49:33+00:00","description":"Serra FM - Todo Mundo Ouve!","breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/#primaryimage","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2021\/02\/vanetealmeida-300x169-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2021\/02\/vanetealmeida-300x169-1.png","width":300,"height":169},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-st-convoca-200-classificados-para-o-vanete-almeida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"ListItem","position":2,"name":"Prefeitura de ST convoca 200 classificados para o Vanete Almeida"}]},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serrafm879.com.br\/serrafm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"R\u00e1dio Serra FM 87,9","url":"https:\/\/serrafm879.com.br\/serrafm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","width":225,"height":225,"caption":"R\u00e1dio Serra FM 87,9"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2021\/02\/vanetealmeida-300x169-1.png","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-64N","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23361"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23361\/revisions"}],"predecessor-version":[{"id":23362,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23361\/revisions\/23362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/4428"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}