{"id":23407,"date":"2025-07-22T17:33:48","date_gmt":"2025-07-22T20:33:48","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23407"},"modified":"2025-07-22T17:33:48","modified_gmt":"2025-07-22T20:33:48","slug":"afogados-recebeu-selo-de-transparencia-do-mp","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/","title":{"rendered":"Afogados recebeu selo de transpar\u00eancia do MP"},"content":{"rendered":"<p>A Prefeitura de\u00a0Afogados da Ingazeira\u00a0recebeu ontem (21) o selo de transpar\u00eancia do Minist\u00e9rio P\u00fablico de Pernambuco pelo repasse volunt\u00e1rio de informa\u00e7\u00f5es ao painel de transpar\u00eancia dos festejos juninos 2025. A entrega aconteceu no audit\u00f3rio da escola judicial de Pernambuco, na ilha Joana Bezerra, no Recife. At\u00e9 ontem, o painel contava com informa\u00e7\u00f5es oriundas das contrata\u00e7\u00f5es de 3.498 artistas, para a realiza\u00e7\u00e3o de 6.215 apresenta\u00e7\u00f5es em 179 munic\u00edpios.<\/p>\n<p>De acordo com o MPPE, o selo busca valorizar os munic\u00edpios que participaram do projeto elaborado pelo Minist\u00e9rio P\u00fablico de Pernambuco, com a colabora\u00e7\u00e3o do Tribunal de Contas do Estado, em parceria com a AMUPE.<\/p>\n<p>O Prefeito de Afogados, Sandrinho Palmeira, foi representado na solenidade pelo Secret\u00e1rio executivo de cultura e esportes, Luciano Pires. \u201cQuero agradecer a toda a equipe da cultura, da gest\u00e3o municipal, pelo empenho e dedica\u00e7\u00e3o, n\u00e3o apenas na realiza\u00e7\u00e3o dos eventos, elogiados por todos, mas tamb\u00e9m pela preocupa\u00e7\u00e3o em dar total transpar\u00eancia aos nossos atos e aos investimentos que fizemos nesse per\u00edodo festivo,\u201d destacou Luciano Pires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de\u00a0Afogados da Ingazeira\u00a0recebeu ontem (21) o selo de transpar\u00eancia do Minist\u00e9rio P\u00fablico de Pernambuco pelo repasse volunt\u00e1rio de informa\u00e7\u00f5es ao painel de transpar\u00eancia dos festejos juninos 2025. A entrega aconteceu no audit\u00f3rio da escola judicial de Pernambuco, na ilha Joana Bezerra, no Recife. At\u00e9 ontem, o painel contava com informa\u00e7\u00f5es oriundas das contrata\u00e7\u00f5es de 3.498 artistas, para a realiza\u00e7\u00e3o de 6.215 apresenta\u00e7\u00f5es em 179 munic\u00edpios. De acordo com o MPPE, o selo busca valorizar os munic\u00edpios que participaram do projeto elaborado pelo Minist\u00e9rio P\u00fablico de Pernambuco, com a colabora\u00e7\u00e3o do Tribunal de Contas do Estado, em parceria com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afogados recebeu selo de transpar\u00eancia do MP - Serra FM 87,9<\/title>\n<meta name=\"description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afogados recebeu selo de transpar\u00eancia do MP - Serra FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/\" \/>\n<meta property=\"og:site_name\" content=\"Serra FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-22T20:33:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"769\" \/>\n\t<meta property=\"og:image:height\" content=\"503\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"serrafm87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"serrafm87\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/\",\"name\":\"Afogados recebeu selo de transpar\u00eancia do MP - Serra FM 87,9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg\",\"datePublished\":\"2025-07-22T20:33:48+00:00\",\"description\":\"Serra FM - Todo Mundo Ouve!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg\",\"width\":769,\"height\":503},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/afogados-recebeu-selo-de-transparencia-do-mp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afogados recebeu selo de transpar\u00eancia do MP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"R\u00e1dio Serra FM 87,9\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"width\":225,\"height\":225,\"caption\":\"R\u00e1dio Serra FM 87,9\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afogados recebeu selo de transpar\u00eancia do MP - Serra FM 87,9","description":"Serra FM - Todo Mundo Ouve!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/","og_locale":"pt_BR","og_type":"article","og_title":"Afogados recebeu selo de transpar\u00eancia do MP - Serra FM 87,9","og_description":"Serra FM - Todo Mundo Ouve!","og_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/","og_site_name":"Serra FM 87,9","article_published_time":"2025-07-22T20:33:48+00:00","og_image":[{"width":769,"height":503,"url":"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg","type":"image\/jpeg"}],"author":"serrafm87","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"serrafm87","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/","name":"Afogados recebeu selo de transpar\u00eancia do MP - Serra FM 87,9","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/#primaryimage"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/#primaryimage"},"thumbnailUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg","datePublished":"2025-07-22T20:33:48+00:00","description":"Serra FM - Todo Mundo Ouve!","breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/#primaryimage","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg","width":769,"height":503},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/afogados-recebeu-selo-de-transparencia-do-mp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"ListItem","position":2,"name":"Afogados recebeu selo de transpar\u00eancia do MP"}]},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serrafm879.com.br\/serrafm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"R\u00e1dio Serra FM 87,9","url":"https:\/\/serrafm879.com.br\/serrafm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","width":225,"height":225,"caption":"R\u00e1dio Serra FM 87,9"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-22-at-11.43.59.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-65x","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23407"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23407\/revisions"}],"predecessor-version":[{"id":23409,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23407\/revisions\/23409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23408"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}