{"id":23434,"date":"2025-07-23T08:08:06","date_gmt":"2025-07-23T11:08:06","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23434"},"modified":"2025-07-23T08:08:53","modified_gmt":"2025-07-23T11:08:53","slug":"23434","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/","title":{"rendered":"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo"},"content":{"rendered":"<div id=\"site\">\n<p><span style=\"font-size: 1.21429rem;\">Tr\u00eas crian\u00e7as, uma de 2, 4 e outra de 6 anos, foram encontradas na noite dessa segunda-feira (21) no munic\u00edpio de Triunfo, Sert\u00e3o do Paje\u00fa, trancadas, chorando e com fome em uma resid\u00eancia do bairro Encruzilhada. Uma delas, tem paralisia cerebral.<\/span><\/p>\n<div class=\"content-container\">\n<section id=\"primary\" class=\"content\">\n<article id=\"post-674489\" class=\"post-674489 post type-post status-publish format-standard has-post-thumbnail hentry category-cotidiano category-destaques category-pagina-inicial category-policia category-serra-talhada\">\n<div class=\"post-content\">\n<p>Segundo informa\u00e7\u00f5es da Pol\u00edcia Militar, a den\u00fancia de abandono foi feita por vizinhos, que ouviram choro e gritos dos menores. O Conselho Tutelar tamb\u00e9m foi acionado.<\/p>\n<p>Segundo o boletim de ocorr\u00eancia, quando a equipe chegou ao local, uma das crian\u00e7as estava comendo as pr\u00f3prias fezes, enquanto as outras gritavam de fome.<\/p>\n<p>A m\u00e3e foi localizada consumindo bebida alco\u00f3lica no centro da cidade, na companhia de amigos. Ao ser questionado sobre o abandono, ela negou afirmando que teria deixado os filhos com uma tia. Ela vai responder por abandono de incapaz.<\/p>\n<p>Informa\u00e7\u00f5es do Farol de Not\u00edcias<\/p>\n<\/div>\n<\/article>\n<\/section>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas crian\u00e7as, uma de 2, 4 e outra de 6 anos, foram encontradas na noite dessa segunda-feira (21) no munic\u00edpio de Triunfo, Sert\u00e3o do Paje\u00fa, trancadas, chorando e com fome em uma resid\u00eancia do bairro Encruzilhada. Uma delas, tem paralisia cerebral. Segundo informa\u00e7\u00f5es da Pol\u00edcia Militar, a den\u00fancia de abandono foi feita por vizinhos, que ouviram choro e gritos dos menores. O Conselho Tutelar tamb\u00e9m foi acionado. Segundo o boletim de ocorr\u00eancia, quando a equipe chegou ao local, uma das crian\u00e7as estava comendo as pr\u00f3prias fezes, enquanto as outras gritavam de fome. A m\u00e3e foi localizada consumindo bebida alco\u00f3lica no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo - Serra FM 87,9<\/title>\n<meta name=\"description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo - Serra FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/\" \/>\n<meta property=\"og:site_name\" content=\"Serra FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-23T11:08:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T11:08:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/transferir-3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"284\" \/>\n\t<meta property=\"og:image:height\" content=\"177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"serrafm87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"serrafm87\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/\",\"name\":\"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo - Serra FM 87,9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/transferir-3-1.jpg\",\"datePublished\":\"2025-07-23T11:08:06+00:00\",\"dateModified\":\"2025-07-23T11:08:53+00:00\",\"description\":\"Serra FM - Todo Mundo Ouve!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/transferir-3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/transferir-3-1.jpg\",\"width\":284,\"height\":177},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/23434\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"R\u00e1dio Serra FM 87,9\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"width\":225,\"height\":225,\"caption\":\"R\u00e1dio Serra FM 87,9\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo - Serra FM 87,9","description":"Serra FM - Todo Mundo Ouve!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/","og_locale":"pt_BR","og_type":"article","og_title":"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo - Serra FM 87,9","og_description":"Serra FM - Todo Mundo Ouve!","og_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/","og_site_name":"Serra FM 87,9","article_published_time":"2025-07-23T11:08:06+00:00","article_modified_time":"2025-07-23T11:08:53+00:00","og_image":[{"width":284,"height":177,"url":"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/transferir-3-1.jpg","type":"image\/jpeg"}],"author":"serrafm87","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"serrafm87","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/","name":"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo - Serra FM 87,9","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/#primaryimage"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/#primaryimage"},"thumbnailUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/transferir-3-1.jpg","datePublished":"2025-07-23T11:08:06+00:00","dateModified":"2025-07-23T11:08:53+00:00","description":"Serra FM - Todo Mundo Ouve!","breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/#primaryimage","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/transferir-3-1.jpg","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/transferir-3-1.jpg","width":284,"height":177},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/23434\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"ListItem","position":2,"name":"Crian\u00e7as em situa\u00e7\u00e3o de abandono s\u00e3o encontradas comendo fezes em Triunfo"}]},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serrafm879.com.br\/serrafm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"R\u00e1dio Serra FM 87,9","url":"https:\/\/serrafm879.com.br\/serrafm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","width":225,"height":225,"caption":"R\u00e1dio Serra FM 87,9"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/transferir-3-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/s7HyXg-23434","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23434"}],"version-history":[{"count":2,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23434\/revisions"}],"predecessor-version":[{"id":23437,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23434\/revisions\/23437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23435"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}