{"id":23505,"date":"2025-07-28T11:04:27","date_gmt":"2025-07-28T14:04:27","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23505"},"modified":"2025-07-28T11:04:27","modified_gmt":"2025-07-28T14:04:27","slug":"apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/","title":{"rendered":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual"},"content":{"rendered":"<p>O ex-prefeito e atual Secret\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\u00e7as pol\u00edticas no ato de assinatura da Ordem de Servi\u00e7o, nesta sexta (25), para a recupera\u00e7\u00e3o da Barragem do Jazigo e da implanta\u00e7\u00e3o do Sistema de Abastecimento de \u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O evento, realizado no Senac da cidade, contou com a presen\u00e7a da Governadora Raquel Lyra, lideran\u00e7as da regi\u00e3o e representantes de diversos setores da sociedade civil.<\/p>\n<p>A convite da pr\u00f3pria governadora, Marconi esteve no centro das articula\u00e7\u00f5es, sendo recebido com entusiasmo por populares, lideran\u00e7as comunit\u00e1rias e agentes p\u00fablicos da regi\u00e3o. O calor humano, os abra\u00e7os e o acolhimento demonstraram que o nome de Marconi Santana ecoa com for\u00e7a crescente em todo o Sert\u00e3o pernambucano \u2014 fruto de um trabalho firme, acess\u00edvel e comprometido com as necessidades reais da popula\u00e7\u00e3o.<\/p>\n<p>Durante o encontro, Raquel Lyra sinalizou, mais uma vez, sintonia com Marconi e reconhecimento ao seu papel como lideran\u00e7a regional. O clima de parceria e confian\u00e7a entre os dois n\u00e3o passou despercebido aos presentes e refor\u00e7a o cen\u00e1rio pol\u00edtico que se desenha para os pr\u00f3ximos meses.<\/p>\n<p>A atua\u00e7\u00e3o de Marconi, que transita com naturalidade entre as bases populares e as altas esferas do Governo do Estado, tem chamado aten\u00e7\u00e3o pelo poder de articula\u00e7\u00e3o e capacidade de construir solu\u00e7\u00f5es reais para os munic\u00edpios do Sert\u00e3o. Em meio aos di\u00e1logos e abra\u00e7os trocados no evento, ficou ainda mais evidente que seu nome surge com vigor como uma refer\u00eancia para representar a regi\u00e3o na Assembleia Legislativa de Pernambuco.<\/p>\n<p>Marconi Santana se destaca como uma lideran\u00e7a comprometida com o desenvolvimento do Sert\u00e3o e cada vez mais conectada com os anseios da popula\u00e7\u00e3o. Com postura firme, di\u00e1logo constante e articula\u00e7\u00e3o eficiente junto ao Governo do Estado, seu nome ganha for\u00e7a e respeito em toda a regi\u00e3o, consolidando-se como uma pot\u00eancia para representar os sertanejos em novas e maiores responsabilidades p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-prefeito e atual Secret\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\u00e7as pol\u00edticas no ato de assinatura da Ordem de Servi\u00e7o, nesta sexta (25), para a recupera\u00e7\u00e3o da Barragem do Jazigo e da implanta\u00e7\u00e3o do Sistema de Abastecimento de \u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O evento, realizado no Senac da cidade, contou com a presen\u00e7a da Governadora Raquel Lyra, lideran\u00e7as da regi\u00e3o e representantes de diversos setores da sociedade civil. A convite da pr\u00f3pria governadora, Marconi esteve no centro das articula\u00e7\u00f5es, sendo recebido com entusiasmo por populares, lideran\u00e7as comunit\u00e1rias e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O ex-prefeito e atual Secret\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\u00e7as pol\u00edticas no ato de assinatura da Ordem de Servi\u00e7o, nesta sexta (25), para a recupera\u00e7\u00e3o da Barragem do Jazigo e da implanta\u00e7\u00e3o do Sistema de Abastecimento de \u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O ex-prefeito e atual Secret\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\u00e7as pol\u00edticas no ato de assinatura da Ordem de Servi\u00e7o, nesta sexta (25), para a recupera\u00e7\u00e3o da Barragem do Jazigo e da implanta\u00e7\u00e3o do Sistema de Abastecimento de \u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/PHOTO-2025-07-25-16-05-29.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#blogposting\",\"name\":\"Apoiado por Raquel Lyra, Marconi Santana \\u00e9 destaque e agita bastidores da pol\\u00edtica estadual - Serra FM 87,9\",\"headline\":\"Apoiado por Raquel Lyra, Marconi Santana \\u00e9 destaque e agita bastidores da pol\\u00edtica estadual\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/PHOTO-2025-07-25-16-05-29.jpg\",\"width\":1024,\"height\":683},\"datePublished\":\"2025-07-28T11:04:27-03:00\",\"dateModified\":\"2025-07-28T11:04:27-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#listItem\",\"name\":\"Apoiado por Raquel Lyra, Marconi Santana \\u00e9 destaque e agita bastidores da pol\\u00edtica estadual\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#listItem\",\"position\":3,\"name\":\"Apoiado por Raquel Lyra, Marconi Santana \\u00e9 destaque e agita bastidores da pol\\u00edtica estadual\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/\",\"name\":\"Apoiado por Raquel Lyra, Marconi Santana \\u00e9 destaque e agita bastidores da pol\\u00edtica estadual - Serra FM 87,9\",\"description\":\"O ex-prefeito e atual Secret\\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\\u00e7as pol\\u00edticas no ato de assinatura da Ordem de Servi\\u00e7o, nesta sexta (25), para a recupera\\u00e7\\u00e3o da Barragem do Jazigo e da implanta\\u00e7\\u00e3o do Sistema de Abastecimento de \\u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/PHOTO-2025-07-25-16-05-29.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#mainImage\",\"width\":1024,\"height\":683},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\\\/#mainImage\"},\"datePublished\":\"2025-07-28T11:04:27-03:00\",\"dateModified\":\"2025-07-28T11:04:27-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual - Serra FM 87,9","description":"O ex-prefeito e atual Secret\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\u00e7as pol\u00edticas no ato de assinatura da Ordem de Servi\u00e7o, nesta sexta (25), para a recupera\u00e7\u00e3o da Barragem do Jazigo e da implanta\u00e7\u00e3o do Sistema de Abastecimento de \u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#blogposting","name":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual - Serra FM 87,9","headline":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/PHOTO-2025-07-25-16-05-29.jpg","width":1024,"height":683},"datePublished":"2025-07-28T11:04:27-03:00","dateModified":"2025-07-28T11:04:27-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#listItem","name":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#listItem","position":3,"name":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/","name":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual - Serra FM 87,9","description":"O ex-prefeito e atual Secret\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\u00e7as pol\u00edticas no ato de assinatura da Ordem de Servi\u00e7o, nesta sexta (25), para a recupera\u00e7\u00e3o da Barragem do Jazigo e da implanta\u00e7\u00e3o do Sistema de Abastecimento de \u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/PHOTO-2025-07-25-16-05-29.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#mainImage","width":1024,"height":683},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/#mainImage"},"datePublished":"2025-07-28T11:04:27-03:00","dateModified":"2025-07-28T11:04:27-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual - Serra FM 87,9","twitter:description":"O ex-prefeito e atual Secret\u00e1rio de Governo de Flores, Marconi Santana, foi uma das principais presen\u00e7as pol\u00edticas no ato de assinatura da Ordem de Servi\u00e7o, nesta sexta (25), para a recupera\u00e7\u00e3o da Barragem do Jazigo e da implanta\u00e7\u00e3o do Sistema de Abastecimento de \u00c1gua do Distrito de Varzinha e comunidades rurais de Serra Talhada. O","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/PHOTO-2025-07-25-16-05-29.jpg"},"aioseo_meta_data":{"post_id":"23505","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:28:13","updated":"2026-07-21 16:28:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tApoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"Apoiado por Raquel Lyra, Marconi Santana \u00e9 destaque e agita bastidores da pol\u00edtica estadual","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/apoiado-por-raquel-lyra-marconi-santana-e-destaque-e-agita-bastidores-da-politica-estadual\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/PHOTO-2025-07-25-16-05-29.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-677","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23505"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23505\/revisions"}],"predecessor-version":[{"id":23507,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23505\/revisions\/23507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23506"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}