{"id":23511,"date":"2025-07-29T08:01:44","date_gmt":"2025-07-29T11:01:44","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23511"},"modified":"2025-07-29T08:01:44","modified_gmt":"2025-07-29T11:01:44","slug":"prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/","title":{"rendered":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar"},"content":{"rendered":"<p>A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\u00e3, quando um c\u00e3o escapou de sua resid\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade.<\/p>\n<p>De acordo com o comunicado, o animal n\u00e3o era de rua e a fuga foi considerada uma fatalidade isolada. Quatro pessoas foram envolvidas na ocorr\u00eancia: uma mulher foi mordida na perna, sem gravidade, e uma crian\u00e7a sofreu escoria\u00e7\u00f5es ao cair durante o susto. A outra crian\u00e7a e a m\u00e3e presentes no local n\u00e3o se feriram.<\/p>\n<p>Populares conseguiram conter o animal at\u00e9 a chegada da equipe da Prefeitura, que realizou a captura de forma segura. O c\u00e3o foi submetido a exames e permanece em observa\u00e7\u00e3o conforme os protocolos de controle de zoonoses, para descartar qualquer risco de transmiss\u00e3o de doen\u00e7as, como a raiva.<\/p>\n<p>A gest\u00e3o municipal refor\u00e7ou o compromisso com a seguran\u00e7a da popula\u00e7\u00e3o, especialmente dos alunos que utilizam o transporte escolar, al\u00e9m de destacar a import\u00e2ncia do controle respons\u00e1vel de animais no munic\u00edpio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\u00e3, quando um c\u00e3o escapou de sua resid\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade. De acordo com o comunicado, o animal n\u00e3o era de rua e a fuga foi considerada uma fatalidade isolada. Quatro pessoas foram envolvidas na ocorr\u00eancia: uma mulher foi mordida na perna, sem gravidade, e uma crian\u00e7a sofreu escoria\u00e7\u00f5es ao cair durante o susto. A outra crian\u00e7a e a m\u00e3e presentes no local n\u00e3o se feriram. Populares conseguiram conter o animal at\u00e9 a chegada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\u00e3, quando um c\u00e3o escapou de sua resid\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade. De acordo com o comunicado, o animal n\u00e3o era de rua e a fuga foi considerada uma fatalidade\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\u00e3, quando um c\u00e3o escapou de sua resid\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade. De acordo com o comunicado, o animal n\u00e3o era de rua e a fuga foi considerada uma fatalidade\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/Captura-de-tela-2025-07-29-080237.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#blogposting\",\"name\":\"Prefeitura de Iguaracy esclarece ataque de c\\u00e3o a pessoas em ponto de transporte escolar - Serra FM 87,9\",\"headline\":\"Prefeitura de Iguaracy esclarece ataque de c\\u00e3o a pessoas em ponto de transporte escolar\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-tela-2025-07-29-080237.png\",\"width\":552,\"height\":363},\"datePublished\":\"2025-07-29T08:01:44-03:00\",\"dateModified\":\"2025-07-29T08:01:44-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#listItem\",\"name\":\"Prefeitura de Iguaracy esclarece ataque de c\\u00e3o a pessoas em ponto de transporte escolar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#listItem\",\"position\":3,\"name\":\"Prefeitura de Iguaracy esclarece ataque de c\\u00e3o a pessoas em ponto de transporte escolar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/\",\"name\":\"Prefeitura de Iguaracy esclarece ataque de c\\u00e3o a pessoas em ponto de transporte escolar - Serra FM 87,9\",\"description\":\"A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\\u00e3, quando um c\\u00e3o escapou de sua resid\\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade. De acordo com o comunicado, o animal n\\u00e3o era de rua e a fuga foi considerada uma fatalidade\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Captura-de-tela-2025-07-29-080237.png\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#mainImage\",\"width\":552,\"height\":363},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/07\\\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\\\/#mainImage\"},\"datePublished\":\"2025-07-29T08:01:44-03:00\",\"dateModified\":\"2025-07-29T08:01:44-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar - Serra FM 87,9","description":"A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\u00e3, quando um c\u00e3o escapou de sua resid\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade. De acordo com o comunicado, o animal n\u00e3o era de rua e a fuga foi considerada uma fatalidade","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#blogposting","name":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar - Serra FM 87,9","headline":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/Captura-de-tela-2025-07-29-080237.png","width":552,"height":363},"datePublished":"2025-07-29T08:01:44-03:00","dateModified":"2025-07-29T08:01:44-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#listItem","name":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#listItem","position":3,"name":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/","name":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar - Serra FM 87,9","description":"A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\u00e3, quando um c\u00e3o escapou de sua resid\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade. De acordo com o comunicado, o animal n\u00e3o era de rua e a fuga foi considerada uma fatalidade","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/Captura-de-tela-2025-07-29-080237.png","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#mainImage","width":552,"height":363},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/#mainImage"},"datePublished":"2025-07-29T08:01:44-03:00","dateModified":"2025-07-29T08:01:44-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar - Serra FM 87,9","twitter:description":"A Prefeitura de Iguaracy divulgou nota oficial nesta segunda-feira (28) esclarecendo um incidente ocorrido pela manh\u00e3, quando um c\u00e3o escapou de sua resid\u00eancia e acabou atacando pessoas que aguardavam o transporte escolar em um ponto da cidade. De acordo com o comunicado, o animal n\u00e3o era de rua e a fuga foi considerada uma fatalidade","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/Captura-de-tela-2025-07-29-080237.png"},"aioseo_meta_data":{"post_id":"23511","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:28:13","updated":"2026-07-21 16:28:13"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPrefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"Prefeitura de Iguaracy esclarece ataque de c\u00e3o a pessoas em ponto de transporte escolar","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/07\/prefeitura-de-iguaracy-esclarece-ataque-de-cao-a-pessoas-em-ponto-de-transporte-escolar\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/07\/Captura-de-tela-2025-07-29-080237.png","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-67d","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23511"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23511\/revisions"}],"predecessor-version":[{"id":23513,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23511\/revisions\/23513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23512"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}