{"id":23578,"date":"2025-08-01T18:45:53","date_gmt":"2025-08-01T21:45:53","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23578"},"modified":"2025-08-01T18:49:19","modified_gmt":"2025-08-01T21:49:19","slug":"marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/","title":{"rendered":"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira"},"content":{"rendered":"<p>O cen\u00e1rio pol\u00edtico do Sert\u00e3o do Paje\u00fa segue em ebuli\u00e7\u00e3o, e um nome tem ganhado cada vez mais for\u00e7a entre lideran\u00e7as e eleitores: Marconi Santana. Com postura firme, di\u00e1logo aberto e discurso coerente, ele tem atra\u00eddo apoios que n\u00e3o apenas somam politicamente, mas simbolizam a consolida\u00e7\u00e3o de um projeto regional robusto e com olhar para o futuro.<\/p>\n<p>Nesta semana, Marconi recebeu o apoio de duas figuras hist\u00f3ricas da pol\u00edtica de Tabira: os ex-vereadores Djalma das Almofadas e Tadeu Sampaio. Ambos t\u00eam trajet\u00f3ria reconhecida e influ\u00eancia que ultrapassa os limites do munic\u00edpio, sendo porta-vozes de uma Tabira que conhece de perto os desafios da regi\u00e3o e busca por representantes comprometidos com solu\u00e7\u00f5es reais.<\/p>\n<p>As ades\u00f5es foram recebidas com entusiasmo e vistas por analistas e lideran\u00e7as como mais uma sinaliza\u00e7\u00e3o clara de que o nome de Marconi Santana cresce de forma consistente como pr\u00e9-candidato a deputado estadual, representando um Sert\u00e3o que quer ser ouvido, respeitado e protagonista nas decis\u00f5es do Estado.<\/p>\n<p>&#8220;Quando l\u00edderes com a experi\u00eancia de Djalma e Tadeu se somam a n\u00f3s, n\u00e3o \u00e9 apenas um apoio \u2014 \u00e9 um sinal de que estamos construindo algo maior, com ra\u00edzes profundas e rumo claro&#8221;, afirmou Marconi, que tem intensificado suas agendas em diversos munic\u00edpios, ampliando di\u00e1logo com comunidades, vereadores, ex-prefeitos e lideran\u00e7as sociais.<\/p>\n<p>A movimenta\u00e7\u00e3o tem despertado aten\u00e7\u00e3o: Marconi tem conseguido o que poucos fazem \u2014 unir diferentes segmentos em torno de uma ideia comum, com base no respeito, na escuta e no compromisso com o bem coletivo.<\/p>\n<p>Djalma e Tadeu tamb\u00e9m foram enf\u00e1ticos: \u201cAcreditamos nesse projeto porque Marconi demonstra coragem, preparo e sensibilidade. O Sert\u00e3o precisa de representa\u00e7\u00e3o forte na Assembleia. Ele tem tudo para ser essa voz\u201d.<\/p>\n<p>Com essa nova ades\u00e3o em Tabira, Marconi Santana n\u00e3o apenas amplia sua base de apoios \u2014 ele se firma, cada vez mais, como o nome que representa uma nova p\u00e1gina na pol\u00edtica sertaneja. E o Sert\u00e3o, ao que tudo indica, j\u00e1 come\u00e7a a escrever esse novo cap\u00edtulo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cen\u00e1rio pol\u00edtico do Sert\u00e3o do Paje\u00fa segue em ebuli\u00e7\u00e3o, e um nome tem ganhado cada vez mais for\u00e7a entre lideran\u00e7as e eleitores: Marconi Santana. Com postura firme, di\u00e1logo aberto e discurso coerente, ele tem atra\u00eddo apoios que n\u00e3o apenas somam politicamente, mas simbolizam a consolida\u00e7\u00e3o de um projeto regional robusto e com olhar para o futuro. Nesta semana, Marconi recebeu o apoio de duas figuras hist\u00f3ricas da pol\u00edtica de Tabira: os ex-vereadores Djalma das Almofadas e Tadeu Sampaio. Ambos t\u00eam trajet\u00f3ria reconhecida e influ\u00eancia que ultrapassa os limites do munic\u00edpio, sendo porta-vozes de uma Tabira que conhece de perto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira - Serra FM 87,9<\/title>\n<meta name=\"description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira - Serra FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/\" \/>\n<meta property=\"og:site_name\" content=\"Serra FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-01T21:45:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T21:49:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-31-19-32-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"serrafm87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"serrafm87\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/\",\"name\":\"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira - Serra FM 87,9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PHOTO-2025-07-31-19-32-48.jpg\",\"datePublished\":\"2025-08-01T21:45:53+00:00\",\"dateModified\":\"2025-08-01T21:49:19+00:00\",\"description\":\"Serra FM - Todo Mundo Ouve!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PHOTO-2025-07-31-19-32-48.jpg\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PHOTO-2025-07-31-19-32-48.jpg\",\"width\":960,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"R\u00e1dio Serra FM 87,9\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"width\":225,\"height\":225,\"caption\":\"R\u00e1dio Serra FM 87,9\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira - Serra FM 87,9","description":"Serra FM - Todo Mundo Ouve!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/","og_locale":"pt_BR","og_type":"article","og_title":"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira - Serra FM 87,9","og_description":"Serra FM - Todo Mundo Ouve!","og_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/","og_site_name":"Serra FM 87,9","article_published_time":"2025-08-01T21:45:53+00:00","article_modified_time":"2025-08-01T21:49:19+00:00","og_image":[{"width":960,"height":1280,"url":"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-31-19-32-48.jpg","type":"image\/jpeg"}],"author":"serrafm87","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"serrafm87","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/","name":"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira - Serra FM 87,9","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/#primaryimage"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/#primaryimage"},"thumbnailUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-31-19-32-48.jpg","datePublished":"2025-08-01T21:45:53+00:00","dateModified":"2025-08-01T21:49:19+00:00","description":"Serra FM - Todo Mundo Ouve!","breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/#primaryimage","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-31-19-32-48.jpg","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-31-19-32-48.jpg","width":960,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marconi-santana-avanca-no-sertao-e-consolida-nome-para-a-alepe-com-adesoes-de-peso-em-tabira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"ListItem","position":2,"name":"Marconi Santana avan\u00e7a no Sert\u00e3o e consolida nome para a Alepe com ades\u00f5es de peso em Tabira"}]},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serrafm879.com.br\/serrafm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"R\u00e1dio Serra FM 87,9","url":"https:\/\/serrafm879.com.br\/serrafm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","width":225,"height":225,"caption":"R\u00e1dio Serra FM 87,9"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PHOTO-2025-07-31-19-32-48.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-68i","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23578"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23578\/revisions"}],"predecessor-version":[{"id":23580,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23578\/revisions\/23580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23579"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}