{"id":23599,"date":"2025-08-04T11:27:04","date_gmt":"2025-08-04T14:27:04","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23599"},"modified":"2025-08-04T11:27:04","modified_gmt":"2025-08-04T14:27:04","slug":"marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","title":{"rendered":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista"},"content":{"rendered":"<p>Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras.<\/p>\n<p>Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva, novo presidente nacional do PT. \u201cVolto empossada, com muito orgulho, no novo Diret\u00f3rio Nacional do PT, agora presidido pelo amigo Edinho Silva. Na presen\u00e7a de nosso presidente Lula, reafirmamos valores que marcam a nossa trajet\u00f3ria\u201d, ressaltou a gestora, em suas redes sociais.<\/p>\n<p>Em outro post, M\u00e1rcia disse ter orgulho da sua hist\u00f3ria como integrante da legenda.<\/p>\n<p>\u201c\u00c9 uma honra fazer parte desse partido que verdadeiramente prioriza a nossa gente\u201d.\u00a0 Mais um encontro com o melhor presidente da Rep\u00fablica que o Brasil j\u00e1 teve. O Partido dos Trabalhadores est\u00e1 cada vez mais forte e unido\u201d, evidenciou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva, novo presidente nacional do PT. \u201cVolto empossada, com muito orgulho, no novo Diret\u00f3rio Nacional do PT, agora presidido pelo amigo Edinho Silva. Na presen\u00e7a de nosso presidente Lula, reafirmamos valores que marcam a nossa trajet\u00f3ria\u201d, ressaltou a gestora, em suas redes sociais. Em outro post, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[144],"tags":[],"class_list":["post-23599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9<\/title>\n<meta name=\"description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/\" \/>\n<meta property=\"og:site_name\" content=\"Serra FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T14:27:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png\" \/>\n\t<meta property=\"og:image:width\" content=\"490\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"serrafm87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"serrafm87\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/\",\"name\":\"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-04-112714.png\",\"datePublished\":\"2025-08-04T14:27:04+00:00\",\"description\":\"Serra FM - Todo Mundo Ouve!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-04-112714.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-04-112714.png\",\"width\":490,\"height\":502},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"R\u00e1dio Serra FM 87,9\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"width\":225,\"height\":225,\"caption\":\"R\u00e1dio Serra FM 87,9\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9","description":"Serra FM - Todo Mundo Ouve!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","og_locale":"pt_BR","og_type":"article","og_title":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9","og_description":"Serra FM - Todo Mundo Ouve!","og_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","og_site_name":"Serra FM 87,9","article_published_time":"2025-08-04T14:27:04+00:00","og_image":[{"width":490,"height":502,"url":"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","type":"image\/png"}],"author":"serrafm87","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"serrafm87","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","name":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#primaryimage"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#primaryimage"},"thumbnailUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","datePublished":"2025-08-04T14:27:04+00:00","description":"Serra FM - Todo Mundo Ouve!","breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#primaryimage","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","width":490,"height":502},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"ListItem","position":2,"name":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista"}]},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serrafm879.com.br\/serrafm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"R\u00e1dio Serra FM 87,9","url":"https:\/\/serrafm879.com.br\/serrafm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","width":225,"height":225,"caption":"R\u00e1dio Serra FM 87,9"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-68D","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23599"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23599\/revisions"}],"predecessor-version":[{"id":23602,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23599\/revisions\/23602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23601"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}