{"id":23599,"date":"2025-08-04T11:27:04","date_gmt":"2025-08-04T14:27:04","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23599"},"modified":"2025-08-04T11:27:04","modified_gmt":"2025-08-04T14:27:04","slug":"marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","title":{"rendered":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista"},"content":{"rendered":"<p>Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras.<\/p>\n<p>Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva, novo presidente nacional do PT. \u201cVolto empossada, com muito orgulho, no novo Diret\u00f3rio Nacional do PT, agora presidido pelo amigo Edinho Silva. Na presen\u00e7a de nosso presidente Lula, reafirmamos valores que marcam a nossa trajet\u00f3ria\u201d, ressaltou a gestora, em suas redes sociais.<\/p>\n<p>Em outro post, M\u00e1rcia disse ter orgulho da sua hist\u00f3ria como integrante da legenda.<\/p>\n<p>\u201c\u00c9 uma honra fazer parte desse partido que verdadeiramente prioriza a nossa gente\u201d.\u00a0 Mais um encontro com o melhor presidente da Rep\u00fablica que o Brasil j\u00e1 teve. O Partido dos Trabalhadores est\u00e1 cada vez mais forte e unido\u201d, evidenciou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva, novo presidente nacional do PT. \u201cVolto empossada, com muito orgulho, no novo Diret\u00f3rio Nacional do PT, agora presidido pelo amigo Edinho Silva. Na presen\u00e7a de nosso presidente Lula, reafirmamos valores que marcam a nossa trajet\u00f3ria\u201d, ressaltou a gestora, em suas redes sociais. Em outro post, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[144],"tags":[],"class_list":["post-23599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva,\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#blogposting\",\"name\":\"M\\u00e1rcia retoma atividade pol\\u00edtica e propaga orgulho de ser petista - Serra FM 87,9\",\"headline\":\"M\\u00e1rcia retoma atividade pol\\u00edtica e propaga orgulho de ser petista\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-04-112714.png\",\"width\":490,\"height\":502},\"datePublished\":\"2025-08-04T11:27:04-03:00\",\"dateModified\":\"2025-08-04T11:27:04-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#webpage\"},\"articleSection\":\"Pol\\u00edtica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#listItem\",\"name\":\"M\\u00e1rcia retoma atividade pol\\u00edtica e propaga orgulho de ser petista\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#listItem\",\"position\":3,\"name\":\"M\\u00e1rcia retoma atividade pol\\u00edtica e propaga orgulho de ser petista\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/politica\\\/#listItem\",\"name\":\"Pol\\u00edtica\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/\",\"name\":\"M\\u00e1rcia retoma atividade pol\\u00edtica e propaga orgulho de ser petista - Serra FM 87,9\",\"description\":\"Ap\\u00f3s um per\\u00edodo de aus\\u00eancia da pauta pol\\u00edtica, em fun\\u00e7\\u00e3o de um problema de sa\\u00fade de uma das filhas, a prefeita de Serra Talhada, M\\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\\u00edlia, do 17\\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \\u00fanica que deu vit\\u00f3ria a Edinho Silva,\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-04-112714.png\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#mainImage\",\"width\":490,\"height\":502},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\\\/#mainImage\"},\"datePublished\":\"2025-08-04T11:27:04-03:00\",\"dateModified\":\"2025-08-04T11:27:04-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9","description":"Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva,","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#blogposting","name":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9","headline":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","width":490,"height":502},"datePublished":"2025-08-04T11:27:04-03:00","dateModified":"2025-08-04T11:27:04-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#webpage"},"articleSection":"Pol\u00edtica"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","name":"Pol\u00edtica"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","position":2,"name":"Pol\u00edtica","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#listItem","name":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#listItem","position":3,"name":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/#listItem","name":"Pol\u00edtica"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/","name":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9","description":"Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva,","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#mainImage","width":490,"height":502},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/#mainImage"},"datePublished":"2025-08-04T11:27:04-03:00","dateModified":"2025-08-04T11:27:04-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista - Serra FM 87,9","twitter:description":"Ap\u00f3s um per\u00edodo de aus\u00eancia da pauta pol\u00edtica, em fun\u00e7\u00e3o de um problema de sa\u00fade de uma das filhas, a prefeita de Serra Talhada, M\u00e1rcia Conrado, retomou a sua agenda, participando, em Bras\u00edlia, do 17\u00ba Congresso Nacional do Partido dos Trabalhadores e das Trabalhadoras. Ela integra a chapa \u00fanica que deu vit\u00f3ria a Edinho Silva,","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png"},"aioseo_meta_data":{"post_id":"23599","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:32:55","updated":"2026-07-21 16:32:55"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/\" title=\"Pol\u00edtica\">Pol\u00edtica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tM\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Pol\u00edtica","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/politica\/"},{"label":"M\u00e1rcia retoma atividade pol\u00edtica e propaga orgulho de ser petista","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/marcia-retoma-atividade-politica-e-propaga-orgulho-de-ser-petista\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-04-112714.png","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-68D","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23599"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23599\/revisions"}],"predecessor-version":[{"id":23602,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23599\/revisions\/23602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23601"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}