{"id":23610,"date":"2025-08-04T16:48:54","date_gmt":"2025-08-04T19:48:54","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23610"},"modified":"2025-08-04T17:12:39","modified_gmt":"2025-08-04T20:12:39","slug":"tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/","title":{"rendered":"TRE PE cassa mandato da vereadora  Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero"},"content":{"rendered":"<p>Em sess\u00e3o ordin\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\u00e7a pela cassa\u00e7\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\u00e7\u00f5es 2024, sob acusa\u00e7\u00e3o de crime eleitoral por fraude na cota de g\u00eanero.<\/p>\n<p>Assim, a decis\u00e3o afeta o mandato da vereadora Juliana Ten\u00f3rio, eleita com 632 votos, que dever\u00e1 ser afastada imediatamente. Apesar disso, o partido poder\u00e1 recorrer da decis\u00e3o do TRE ao TSE (Tribunal Superior Eleitoral), em Bras\u00edlia.<\/p>\n<p>Em Recife, o TRE rejeitou, na verdade, as alega\u00e7\u00f5es da defesa do Solidariedade frente \u00e0 decis\u00e3o tomada em primeira inst\u00e2ncia na 71\u00aa Zona Eleitoral de Serra Talhada.<\/p>\n<p>Na decis\u00e3o local, o juiz Marcus C\u00e9sar Sarmento Gadelha julgou improcedentes os embargos de declara\u00e7\u00e3o do Solidariedade na A\u00e7\u00e3o de Investiga\u00e7\u00e3o Judicial Eleitoral (Aije) que apurava fraude \u00e0 cota de g\u00eanero nas elei\u00e7\u00f5es de 2024.<\/p>\n<p>No TRE, a relatora do processo foi a desembargadora eleitoral Karina Arag\u00e3o que, no seu voto, manteve integralmente a senten\u00e7a proferida pela 71\u00aa Zona Eleitoral de Serra Talhada, sendo acompanhada pelo pleno da corte.<\/p>\n<p><strong>CONSEQU\u00caNCIAS<\/strong><\/p>\n<p>A vereadora Juliana Ten\u00f3rio se afasta imediatamente do mandato por fraude a cota de g\u00eanero e ainda sofre a penalidade de inelegibilidade por 8 anos, tamb\u00e9m aplicada a seu marido, o m\u00e9dico Waldir Ten\u00f3rio J\u00fanior e presidente do Solidariedade, e as candidatas J\u00e9ssica Bianca e Michele Barros, por terem todos concorrido com a fraude.<\/p>\n<p><strong>Acompanhe as seguintes consequ\u00eancias:<\/strong><\/p>\n<p>i) Anula\u00e7\u00e3o dos votos de todos os candidatos a verean\u00e7a do partido Solidariedade;<br \/>\n(ii) Desconstitui\u00e7\u00e3o dos diplomas de Juliana Ten\u00f3rio e demais suplentes do partido;<br \/>\n(iii) Declara\u00e7\u00e3o de inelegibilidade por 08 anos de Waldir Ten\u00f3rio, Juliana Ten\u00f3rio, Jessica Bianca e Michele Barros;<br \/>\n(iv) Desconstitui\u00e7\u00e3o do DRAP; e<br \/>\n(v) Rec\u00e1lculo do quociente eleitoral e partid\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Farol de Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sess\u00e3o ordin\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\u00e7a pela cassa\u00e7\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\u00e7\u00f5es 2024, sob acusa\u00e7\u00e3o de crime eleitoral por fraude na cota de g\u00eanero. Assim, a decis\u00e3o afeta o mandato da vereadora Juliana Ten\u00f3rio, eleita com 632 votos, que dever\u00e1 ser afastada imediatamente. Apesar disso, o partido poder\u00e1 recorrer da decis\u00e3o do TRE ao TSE (Tribunal Superior Eleitoral), em Bras\u00edlia. Em Recife, o TRE rejeitou, na verdade, as alega\u00e7\u00f5es da defesa do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Em sess\u00e3o ordin\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\u00e7a pela cassa\u00e7\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\u00e7\u00f5es 2024, sob acusa\u00e7\u00e3o de crime eleitoral por fraude na cota de g\u00eanero. Assim, a decis\u00e3o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"TRE PE cassa mandato da vereadora Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Em sess\u00e3o ordin\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\u00e7a pela cassa\u00e7\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\u00e7\u00f5es 2024, sob acusa\u00e7\u00e3o de crime eleitoral por fraude na cota de g\u00eanero. Assim, a decis\u00e3o\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/download-2.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#blogposting\",\"name\":\"TRE PE cassa mandato da vereadora Juliana Ten\\u00f3rio do Solidariedade por fraude \\u00e0 Cota de G\\u00eanero - Serra FM 87,9\",\"headline\":\"TRE PE cassa mandato da vereadora  Juliana Ten\\u00f3rio do Solidariedade por fraude \\u00e0 Cota de G\\u00eanero\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/download-2.jpg\",\"width\":275,\"height\":183},\"datePublished\":\"2025-08-04T16:48:54-03:00\",\"dateModified\":\"2025-08-04T17:12:39-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#listItem\",\"name\":\"TRE PE cassa mandato da vereadora  Juliana Ten\\u00f3rio do Solidariedade por fraude \\u00e0 Cota de G\\u00eanero\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#listItem\",\"position\":3,\"name\":\"TRE PE cassa mandato da vereadora  Juliana Ten\\u00f3rio do Solidariedade por fraude \\u00e0 Cota de G\\u00eanero\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/\",\"name\":\"TRE PE cassa mandato da vereadora Juliana Ten\\u00f3rio do Solidariedade por fraude \\u00e0 Cota de G\\u00eanero - Serra FM 87,9\",\"description\":\"Em sess\\u00e3o ordin\\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\\u00e7a pela cassa\\u00e7\\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\\u00e7\\u00f5es 2024, sob acusa\\u00e7\\u00e3o de crime eleitoral por fraude na cota de g\\u00eanero. Assim, a decis\\u00e3o\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/download-2.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#mainImage\",\"width\":275,\"height\":183},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\\\/#mainImage\"},\"datePublished\":\"2025-08-04T16:48:54-03:00\",\"dateModified\":\"2025-08-04T17:12:39-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TRE PE cassa mandato da vereadora Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero - Serra FM 87,9","description":"Em sess\u00e3o ordin\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\u00e7a pela cassa\u00e7\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\u00e7\u00f5es 2024, sob acusa\u00e7\u00e3o de crime eleitoral por fraude na cota de g\u00eanero. Assim, a decis\u00e3o","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#blogposting","name":"TRE PE cassa mandato da vereadora Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero - Serra FM 87,9","headline":"TRE PE cassa mandato da vereadora  Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/download-2.jpg","width":275,"height":183},"datePublished":"2025-08-04T16:48:54-03:00","dateModified":"2025-08-04T17:12:39-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#listItem","name":"TRE PE cassa mandato da vereadora  Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#listItem","position":3,"name":"TRE PE cassa mandato da vereadora  Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/","name":"TRE PE cassa mandato da vereadora Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero - Serra FM 87,9","description":"Em sess\u00e3o ordin\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\u00e7a pela cassa\u00e7\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\u00e7\u00f5es 2024, sob acusa\u00e7\u00e3o de crime eleitoral por fraude na cota de g\u00eanero. Assim, a decis\u00e3o","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/download-2.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#mainImage","width":275,"height":183},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/#mainImage"},"datePublished":"2025-08-04T16:48:54-03:00","dateModified":"2025-08-04T17:12:39-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"TRE PE cassa mandato da vereadora Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero - Serra FM 87,9","twitter:description":"Em sess\u00e3o ordin\u00e1ria nesta segunda-feira (4), o Tribunal Regional Eleitoral de Pernambuco (TRE) decidiu, por unanimidade, negar provimento ao recurso do partido Solidariedade e manter a senten\u00e7a pela cassa\u00e7\u00e3o da chapa do Solidariedade em Serra Talhada na disputa das elei\u00e7\u00f5es 2024, sob acusa\u00e7\u00e3o de crime eleitoral por fraude na cota de g\u00eanero. Assim, a decis\u00e3o","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/download-2.jpg"},"aioseo_meta_data":{"post_id":"23610","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:34:31","updated":"2026-07-21 16:34:31"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTRE PE cassa mandato da vereadora  Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"TRE PE cassa mandato da vereadora  Juliana Ten\u00f3rio do Solidariedade por fraude \u00e0 Cota de G\u00eanero","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/tre-confirma-crime-do-solidariedade-em-st-e-cassa-juliana-tenorio\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/download-2.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-68O","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23610"}],"version-history":[{"count":5,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23610\/revisions"}],"predecessor-version":[{"id":23616,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23610\/revisions\/23616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23611"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}