{"id":23642,"date":"2025-08-05T11:00:55","date_gmt":"2025-08-05T14:00:55","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23642"},"modified":"2025-08-05T11:00:55","modified_gmt":"2025-08-05T14:00:55","slug":"ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/","title":{"rendered":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada"},"content":{"rendered":"<p>O Programa de Est\u00e1gio do Minist\u00e9rio P\u00fablico Federal est\u00e1 com processo seletivo aberto. Podem participar da sele\u00e7\u00e3o, estudantes de gradua\u00e7\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\u00e3o nas cidades de Caruaru, Serra Talhada e Recife.<\/p>\n<p>As inscri\u00e7\u00f5es iniciaram nesta segunda-feira (4) e v\u00e3o at\u00e9 o dia 31 de agosto. As provas acontecem de forma remota, no dia 21 de setembro. O programa oferta uma bolsa aux\u00edlio, no valor de R$ 1.027, 82 e aux\u00edlio transporte no valor de R$ 11,58.<\/p>\n<p>Para mais informa\u00e7\u00f5es, acesse o site do\u00a0<a href=\"https:\/\/www.mpf.mp.br\/pe\/estagie-conosco\" target=\"_blank\" rel=\"noopener\">Minist\u00e9rio P\u00fablico Federal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Programa de Est\u00e1gio do Minist\u00e9rio P\u00fablico Federal est\u00e1 com processo seletivo aberto. Podem participar da sele\u00e7\u00e3o, estudantes de gradua\u00e7\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\u00e3o nas cidades de Caruaru, Serra Talhada e Recife. As inscri\u00e7\u00f5es iniciaram nesta segunda-feira (4) e v\u00e3o at\u00e9 o dia 31 de agosto. As provas acontecem de forma remota, no dia 21 de setembro. O programa oferta uma bolsa aux\u00edlio, no valor de R$ 1.027, 82 e aux\u00edlio transporte no valor de R$ 11,58. Para mais informa\u00e7\u00f5es, acesse o site do\u00a0Minist\u00e9rio P\u00fablico Federal<\/p>\n","protected":false},"author":2,"featured_media":22097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Programa de Est\u00e1gio do Minist\u00e9rio P\u00fablico Federal est\u00e1 com processo seletivo aberto. Podem participar da sele\u00e7\u00e3o, estudantes de gradua\u00e7\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\u00e3o nas cidades de Caruaru, Serra Talhada e Recife. As inscri\u00e7\u00f5es iniciaram nesta segunda-feira (4) e v\u00e3o at\u00e9 o dia 31 de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Programa de Est\u00e1gio do Minist\u00e9rio P\u00fablico Federal est\u00e1 com processo seletivo aberto. Podem participar da sele\u00e7\u00e3o, estudantes de gradua\u00e7\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\u00e3o nas cidades de Caruaru, Serra Talhada e Recife. As inscri\u00e7\u00f5es iniciaram nesta segunda-feira (4) e v\u00e3o at\u00e9 o dia 31 de\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/04\/serra-talhada.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#blogposting\",\"name\":\"Minist\\u00e9rio P\\u00fablico abre vagas de est\\u00e1gio em cidades de PE e inclui Serra Talhada - Serra FM 87,9\",\"headline\":\"Minist\\u00e9rio P\\u00fablico abre vagas de est\\u00e1gio em cidades de PE e inclui Serra Talhada\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/serra-talhada.jpeg\",\"width\":640,\"height\":435},\"datePublished\":\"2025-08-05T11:00:55-03:00\",\"dateModified\":\"2025-08-05T11:00:55-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#listItem\",\"name\":\"Minist\\u00e9rio P\\u00fablico abre vagas de est\\u00e1gio em cidades de PE e inclui Serra Talhada\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#listItem\",\"position\":3,\"name\":\"Minist\\u00e9rio P\\u00fablico abre vagas de est\\u00e1gio em cidades de PE e inclui Serra Talhada\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/\",\"name\":\"Minist\\u00e9rio P\\u00fablico abre vagas de est\\u00e1gio em cidades de PE e inclui Serra Talhada - Serra FM 87,9\",\"description\":\"O Programa de Est\\u00e1gio do Minist\\u00e9rio P\\u00fablico Federal est\\u00e1 com processo seletivo aberto. Podem participar da sele\\u00e7\\u00e3o, estudantes de gradua\\u00e7\\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\\u00e3o nas cidades de Caruaru, Serra Talhada e Recife. As inscri\\u00e7\\u00f5es iniciaram nesta segunda-feira (4) e v\\u00e3o at\\u00e9 o dia 31 de\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/serra-talhada.jpeg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#mainImage\",\"width\":640,\"height\":435},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\\\/#mainImage\"},\"datePublished\":\"2025-08-05T11:00:55-03:00\",\"dateModified\":\"2025-08-05T11:00:55-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada - Serra FM 87,9","description":"O Programa de Est\u00e1gio do Minist\u00e9rio P\u00fablico Federal est\u00e1 com processo seletivo aberto. Podem participar da sele\u00e7\u00e3o, estudantes de gradua\u00e7\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\u00e3o nas cidades de Caruaru, Serra Talhada e Recife. As inscri\u00e7\u00f5es iniciaram nesta segunda-feira (4) e v\u00e3o at\u00e9 o dia 31 de","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#blogposting","name":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada - Serra FM 87,9","headline":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/04\/serra-talhada.jpeg","width":640,"height":435},"datePublished":"2025-08-05T11:00:55-03:00","dateModified":"2025-08-05T11:00:55-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#listItem","name":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#listItem","position":3,"name":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/","name":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada - Serra FM 87,9","description":"O Programa de Est\u00e1gio do Minist\u00e9rio P\u00fablico Federal est\u00e1 com processo seletivo aberto. Podem participar da sele\u00e7\u00e3o, estudantes de gradua\u00e7\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\u00e3o nas cidades de Caruaru, Serra Talhada e Recife. As inscri\u00e7\u00f5es iniciaram nesta segunda-feira (4) e v\u00e3o at\u00e9 o dia 31 de","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/04\/serra-talhada.jpeg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#mainImage","width":640,"height":435},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/#mainImage"},"datePublished":"2025-08-05T11:00:55-03:00","dateModified":"2025-08-05T11:00:55-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada - Serra FM 87,9","twitter:description":"O Programa de Est\u00e1gio do Minist\u00e9rio P\u00fablico Federal est\u00e1 com processo seletivo aberto. Podem participar da sele\u00e7\u00e3o, estudantes de gradua\u00e7\u00e3o dos cursos de Secretariado e Direito. Para o curso de Direito, as oportunidades s\u00e3o nas cidades de Caruaru, Serra Talhada e Recife. As inscri\u00e7\u00f5es iniciaram nesta segunda-feira (4) e v\u00e3o at\u00e9 o dia 31 de","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/04\/serra-talhada.jpeg"},"aioseo_meta_data":{"post_id":"23642","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:34:31","updated":"2026-07-21 16:34:31"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMinist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"Minist\u00e9rio P\u00fablico abre vagas de est\u00e1gio em cidades de PE e inclui Serra Talhada","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ministerio-publico-abre-vagas-de-estagio-em-cidades-de-pe-e-inclui-serra-talhada\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/04\/serra-talhada.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-69k","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23642"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23642\/revisions"}],"predecessor-version":[{"id":23643,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23642\/revisions\/23643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/22097"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}