{"id":23660,"date":"2025-08-06T10:26:11","date_gmt":"2025-08-06T13:26:11","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23660"},"modified":"2025-08-06T10:26:11","modified_gmt":"2025-08-06T13:26:11","slug":"pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/","title":{"rendered":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es"},"content":{"rendered":"<p>Um esquema criminoso teria causado um preju\u00edzo de mais de R$ 5 milh\u00f5es aos cofres p\u00fablicos por meio de cobran\u00e7as indevidas de servi\u00e7os de despachante, \u00e9 o que afirma a Pol\u00edcia Federal (PF).<\/p>\n<p>Segundo o \u00f3rg\u00e3o, aposentados e pensionistas buscavam ag\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\u00e9stimos e se depararam com uma \u201ctrava em seu benef\u00edcio\u201d, que s\u00f3 era liberado mediante o pagamento de uma taxa.<\/p>\n<p>As investiga\u00e7\u00f5es, iniciadas em 2023 a partir de levantamentos realizados pelo N\u00facleo Regional de Intelig\u00eancia da Previd\u00eancia Social em Pernambuco, culminaram com a deflagra\u00e7\u00e3o, nesta ter\u00e7a-feira (5), da Opera\u00e7\u00e3o Ap\u00f3fis.<\/p>\n<p>Ao todo, foram cumpridos 13 mandados de busca e apreens\u00e3o nas cidades do Recife, Cabo de Santo Agostinho, S\u00e3o Paulo, Belo Horizonte, Bras\u00edlia e Ponta Grossa. Para cumprir as ordens judiciais, foram mobilizados 65 policiais federais e 5 servidores t\u00e9cnicos do Minist\u00e9rio da Previd\u00eancia Social.<\/p>\n<p>De acordo com a investiga\u00e7\u00e3o, um servidor do INSS, morador do Grande Recife, facilitava o esquema para que houvesse \u00eaxito nas a\u00e7\u00f5es. \u201cOs aposentados e pensionistas tinham ci\u00eancia do empr\u00e9stimo e queriam, s\u00f3 que por interven\u00e7\u00e3o do servidor p\u00fablico, era colocada, propositalmente, uma trava no benef\u00edcio\u201d, detalhou o delegado da Pol\u00edcia Federal M\u00e1rcio Ten\u00f3rio.<\/p>\n<p>A partir da\u00ed, segundo o delegado, entraria a participa\u00e7\u00e3o de correspondentes banc\u00e1rios, que atuariam como despachantes. \u201cAssim que o aposentado ou pensionista buscava esse correspondente, o servidor do INSS entrava no site da autarquia e desbloqueava o site, permitindo a libera\u00e7\u00e3o do empr\u00e9stimo\u201d, continuou.<\/p>\n<p>No entanto, para a libera\u00e7\u00e3o do empr\u00e9stimo, o despachante solicitava um pagamento, de valor n\u00e3o informado pela PF. \u201cO aposentado\/pensionista se via obrigado a pagar por aquele suposto servi\u00e7o de despacho para que o empr\u00e9stimo fosse liberado, por puro desconhecimento\u201d, disse.<\/p>\n<p>Os investigados podem responder por diversos crimes, entre eles: corrup\u00e7\u00e3o ativa, estelionato, inser\u00e7\u00e3o de dados falsos em sistemas de informa\u00e7\u00e3o, viola\u00e7\u00e3o de sigilo profissional, organiza\u00e7\u00e3o criminosa e lavagem de dinheiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um esquema criminoso teria causado um preju\u00edzo de mais de R$ 5 milh\u00f5es aos cofres p\u00fablicos por meio de cobran\u00e7as indevidas de servi\u00e7os de despachante, \u00e9 o que afirma a Pol\u00edcia Federal (PF). Segundo o \u00f3rg\u00e3o, aposentados e pensionistas buscavam ag\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\u00e9stimos e se depararam com uma \u201ctrava em seu benef\u00edcio\u201d, que s\u00f3 era liberado mediante o pagamento de uma taxa. As investiga\u00e7\u00f5es, iniciadas em 2023 a partir de levantamentos realizados pelo N\u00facleo Regional de Intelig\u00eancia da Previd\u00eancia Social em Pernambuco, culminaram com a deflagra\u00e7\u00e3o, nesta ter\u00e7a-feira (5), da Opera\u00e7\u00e3o Ap\u00f3fis. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Um esquema criminoso teria causado um preju\u00edzo de mais de R$ 5 milh\u00f5es aos cofres p\u00fablicos por meio de cobran\u00e7as indevidas de servi\u00e7os de despachante, \u00e9 o que afirma a Pol\u00edcia Federal (PF). Segundo o \u00f3rg\u00e3o, aposentados e pensionistas buscavam ag\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\u00e9stimos e se depararam com\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Um esquema criminoso teria causado um preju\u00edzo de mais de R$ 5 milh\u00f5es aos cofres p\u00fablicos por meio de cobran\u00e7as indevidas de servi\u00e7os de despachante, \u00e9 o que afirma a Pol\u00edcia Federal (PF). Segundo o \u00f3rg\u00e3o, aposentados e pensionistas buscavam ag\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\u00e9stimos e se depararam com\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/01\/pfbr.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#blogposting\",\"name\":\"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\\u00f5es - Serra FM 87,9\",\"headline\":\"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\\u00f5es\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/pfbr.jpg\",\"width\":840,\"height\":480},\"datePublished\":\"2025-08-06T10:26:11-03:00\",\"dateModified\":\"2025-08-06T10:26:11-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#listItem\",\"name\":\"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\\u00f5es\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#listItem\",\"position\":3,\"name\":\"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\\u00f5es\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/\",\"name\":\"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\\u00f5es - Serra FM 87,9\",\"description\":\"Um esquema criminoso teria causado um preju\\u00edzo de mais de R$ 5 milh\\u00f5es aos cofres p\\u00fablicos por meio de cobran\\u00e7as indevidas de servi\\u00e7os de despachante, \\u00e9 o que afirma a Pol\\u00edcia Federal (PF). Segundo o \\u00f3rg\\u00e3o, aposentados e pensionistas buscavam ag\\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\\u00e9stimos e se depararam com\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/pfbr.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#mainImage\",\"width\":840,\"height\":480},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\\\/#mainImage\"},\"datePublished\":\"2025-08-06T10:26:11-03:00\",\"dateModified\":\"2025-08-06T10:26:11-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es - Serra FM 87,9","description":"Um esquema criminoso teria causado um preju\u00edzo de mais de R$ 5 milh\u00f5es aos cofres p\u00fablicos por meio de cobran\u00e7as indevidas de servi\u00e7os de despachante, \u00e9 o que afirma a Pol\u00edcia Federal (PF). Segundo o \u00f3rg\u00e3o, aposentados e pensionistas buscavam ag\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\u00e9stimos e se depararam com","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#blogposting","name":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es - Serra FM 87,9","headline":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/01\/pfbr.jpg","width":840,"height":480},"datePublished":"2025-08-06T10:26:11-03:00","dateModified":"2025-08-06T10:26:11-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#listItem","name":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#listItem","position":3,"name":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/","name":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es - Serra FM 87,9","description":"Um esquema criminoso teria causado um preju\u00edzo de mais de R$ 5 milh\u00f5es aos cofres p\u00fablicos por meio de cobran\u00e7as indevidas de servi\u00e7os de despachante, \u00e9 o que afirma a Pol\u00edcia Federal (PF). Segundo o \u00f3rg\u00e3o, aposentados e pensionistas buscavam ag\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\u00e9stimos e se depararam com","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/01\/pfbr.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#mainImage","width":840,"height":480},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/#mainImage"},"datePublished":"2025-08-06T10:26:11-03:00","dateModified":"2025-08-06T10:26:11-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es - Serra FM 87,9","twitter:description":"Um esquema criminoso teria causado um preju\u00edzo de mais de R$ 5 milh\u00f5es aos cofres p\u00fablicos por meio de cobran\u00e7as indevidas de servi\u00e7os de despachante, \u00e9 o que afirma a Pol\u00edcia Federal (PF). Segundo o \u00f3rg\u00e3o, aposentados e pensionistas buscavam ag\u00eancias do Instituto Nacional do Seguro Social (INSS) para conseguirem empr\u00e9stimos e se depararam com","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/01\/pfbr.jpg"},"aioseo_meta_data":{"post_id":"23660","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:37:38","updated":"2026-07-21 16:37:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"PF desarticula esquema que lesou aposentados e gerou rombo de R$ 5 milh\u00f5es","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/pf-desarticula-esquema-que-lesou-aposentados-e-gerou-rombo-de-r-5-milhoes\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/01\/pfbr.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-69C","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23660"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23660\/revisions"}],"predecessor-version":[{"id":23661,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23660\/revisions\/23661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/20210"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}