{"id":23690,"date":"2025-08-06T18:13:18","date_gmt":"2025-08-06T21:13:18","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23690"},"modified":"2025-08-06T18:13:48","modified_gmt":"2025-08-06T21:13:48","slug":"ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/","title":{"rendered":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado"},"content":{"rendered":"<p>O Instituto Federal do Sert\u00e3o Pernambucano (IFSert\u00e3oPE) abre inscri\u00e7\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\u00e9cnicos gratuitos nas modalidades\u00a0Ensino M\u00e9dio Integrado\u00a0e\u00a0Subsequente\u00a0(p\u00f3s-<wbr \/>m\u00e9dio), com ingresso em 2026. As inscri\u00e7\u00f5es seguir\u00e3o at\u00e9 o dia 14 de setembro.<\/p>\n<p>No campus Serra Talhada, est\u00e3o sendo ofertados quatro cursos presenciais e gratuitos:<\/p>\n<ul>\n<li>Ensino M\u00e9dio Integrado ao T\u00e9cnico em Edifica\u00e7\u00f5es \u2013 Manh\u00e3 (36 vagas)<\/li>\n<li>Ensino M\u00e9dio Integrado ao T\u00e9cnico em Mec\u00e2nica \u2013 Tarde (36 vagas)<\/li>\n<li>Ensino M\u00e9dio Integrado ao T\u00e9cnico em Log\u00edstica \u2013 Manh\u00e3 (36 vagas)<\/li>\n<li>Curso T\u00e9cnico Subsequente em Refrigera\u00e7\u00e3o e Climatiza\u00e7\u00e3o \u2013 Noite (36 vagas)<\/li>\n<\/ul>\n<p>A modalidade Ensino M\u00e9dio Integrado \u00e9 voltada para estudantes que est\u00e3o concluindo ou j\u00e1 conclu\u00edram o Ensino Fundamental (9\u00ba ano), esses estudantes come\u00e7ar\u00e3o as aulas em fevereiro de 2026. J\u00e1 o curso Subsequente \u00e9 direcionado a quem j\u00e1 concluiu o Ensino M\u00e9dio e as aulas ter\u00e3o in\u00edcio em agosto de 2026.<\/p>\n<p>A sele\u00e7\u00e3o para os cursos M\u00e9dio Integrado ser\u00e1 feita por\u00a0an\u00e1lise do hist\u00f3rico escolar, levando em considera\u00e7\u00e3o as notas de L\u00edngua Portuguesa e Matem\u00e1tica do 7\u00ba e 8\u00ba anos. Para o curso subsequente, o crit\u00e9rio de classifica\u00e7\u00e3o ser\u00e1 o\u00a0sorteio eletr\u00f4nico\u00a0entre os inscritos. Para se inscrever, os interessados devem acessar o site\u00a0<a href=\"https:\/\/selecao.ifsertaope.edu.br\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/selecao.ifsertaope.edu.br\/&amp;source=gmail&amp;ust=1754592368078000&amp;usg=AOvVaw3z-OV1w3vFd5awMOFbBn4g\">https:\/\/selecao.<wbr \/>ifsertaope.edu.br<\/a>\u00a0e seguir as orienta\u00e7\u00f5es do edital. O processo \u00e9 totalmente gratuito.<\/p>\n<p>O processo contempla ampla concorr\u00eancia e reserva de vagas para candidatos de escolas p\u00fablicas, pessoas com defici\u00eancia, ind\u00edgenas, quilombolas, al\u00e9m de cotas raciais e de renda, conforme legisla\u00e7\u00e3o vigente. Com oferta de vagas em Floresta, Ouricuri, Petrolina, Salgueiro, Santa Maria da Boa Vista e Petrolina Zona Rural, o IFSert\u00e3oPE se destaca por levar educa\u00e7\u00e3o de qualidade a diferentes regi\u00f5es do estado. Em Serra Talhada, os cursos fortalecem a qualifica\u00e7\u00e3o t\u00e9cnica e o acesso ao ensino p\u00fablico federal.<\/p>\n<p>Para todos os candidatos que desejam se inscrever \u00e9 fundamental ler o edital da sele\u00e7\u00e3o.<\/p>\n<p><a href=\"https:\/\/ifsertaope.edu.br\/wp-content\/uploads\/2025\/08\/Edital-no-101.2025.pdf\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/ifsertaope.edu.br\/wp-content\/uploads\/2025\/08\/Edital-no-101.2025.pdf&amp;source=gmail&amp;ust=1754592368078000&amp;usg=AOvVaw0DKe-TqnBU_HXp_fjwBp1l\">\u00a0Clique aqui para ter acesso ao Edital 101\/2025<\/a>\u00a0\u2013\u00a0 para os cursos de Ensino M\u00e9dio Integrado.<br \/>\n<a href=\"https:\/\/ifsertaope.edu.br\/wp-content\/uploads\/2025\/08\/Edital-no-102.2025.pdf\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/ifsertaope.edu.br\/wp-content\/uploads\/2025\/08\/Edital-no-102.2025.pdf&amp;source=gmail&amp;ust=1754592368078000&amp;usg=AOvVaw3a2vY55izlqbpUSqM1qVeN\">Clique aqui para ter acesso ao Edital 102\/2025<\/a>\u00a0\u2013 para os cursos Subsequentes.<\/p>\n<h6><em>Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Sert\u00e3o Pernambucano<br \/>\n<\/em><\/h6>\n<h6><em>Campus Serra Talhada\u00a0<\/em><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Federal do Sert\u00e3o Pernambucano (IFSert\u00e3oPE) abre inscri\u00e7\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\u00e9cnicos gratuitos nas modalidades\u00a0Ensino M\u00e9dio Integrado\u00a0e\u00a0Subsequente\u00a0(p\u00f3s-m\u00e9dio), com ingresso em 2026. As inscri\u00e7\u00f5es seguir\u00e3o at\u00e9 o dia 14 de setembro. No campus Serra Talhada, est\u00e3o sendo ofertados quatro cursos presenciais e gratuitos: Ensino M\u00e9dio Integrado ao T\u00e9cnico em Edifica\u00e7\u00f5es \u2013 Manh\u00e3 (36 vagas) Ensino M\u00e9dio Integrado ao T\u00e9cnico em Mec\u00e2nica \u2013 Tarde (36 vagas) Ensino M\u00e9dio Integrado ao T\u00e9cnico em Log\u00edstica \u2013 Manh\u00e3 (36 vagas) Curso T\u00e9cnico Subsequente em Refrigera\u00e7\u00e3o e Climatiza\u00e7\u00e3o \u2013 Noite (36 vagas) A modalidade Ensino M\u00e9dio Integrado \u00e9 voltada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Instituto Federal do Sert\u00e3o Pernambucano (IFSert\u00e3oPE) abre inscri\u00e7\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\u00e9cnicos gratuitos nas modalidades Ensino M\u00e9dio Integrado e Subsequente (p\u00f3s-m\u00e9dio), com ingresso em 2026. As inscri\u00e7\u00f5es seguir\u00e3o at\u00e9 o dia 14 de setembro. No campus Serra Talhada, est\u00e3o sendo ofertados quatro cursos presenciais e gratuitos: Ensino M\u00e9dio Integrado ao T\u00e9cnico em\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Instituto Federal do Sert\u00e3o Pernambucano (IFSert\u00e3oPE) abre inscri\u00e7\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\u00e9cnicos gratuitos nas modalidades Ensino M\u00e9dio Integrado e Subsequente (p\u00f3s-m\u00e9dio), com ingresso em 2026. As inscri\u00e7\u00f5es seguir\u00e3o at\u00e9 o dia 14 de setembro. No campus Serra Talhada, est\u00e3o sendo ofertados quatro cursos presenciais e gratuitos: Ensino M\u00e9dio Integrado ao T\u00e9cnico em\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PS-2026.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#blogposting\",\"name\":\"IFSert\\u00e3oPE abre inscri\\u00e7\\u00f5es para cursos t\\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado - Serra FM 87,9\",\"headline\":\"IFSert\\u00e3oPE abre inscri\\u00e7\\u00f5es para cursos t\\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PS-2026.jpeg\",\"width\":1024,\"height\":1024},\"datePublished\":\"2025-08-06T18:13:18-03:00\",\"dateModified\":\"2025-08-06T18:13:48-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#listItem\",\"name\":\"IFSert\\u00e3oPE abre inscri\\u00e7\\u00f5es para cursos t\\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#listItem\",\"position\":3,\"name\":\"IFSert\\u00e3oPE abre inscri\\u00e7\\u00f5es para cursos t\\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/\",\"name\":\"IFSert\\u00e3oPE abre inscri\\u00e7\\u00f5es para cursos t\\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado - Serra FM 87,9\",\"description\":\"O Instituto Federal do Sert\\u00e3o Pernambucano (IFSert\\u00e3oPE) abre inscri\\u00e7\\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\\u00e9cnicos gratuitos nas modalidades Ensino M\\u00e9dio Integrado e Subsequente (p\\u00f3s-m\\u00e9dio), com ingresso em 2026. As inscri\\u00e7\\u00f5es seguir\\u00e3o at\\u00e9 o dia 14 de setembro. No campus Serra Talhada, est\\u00e3o sendo ofertados quatro cursos presenciais e gratuitos: Ensino M\\u00e9dio Integrado ao T\\u00e9cnico em\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/PS-2026.jpeg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#mainImage\",\"width\":1024,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\\\/#mainImage\"},\"datePublished\":\"2025-08-06T18:13:18-03:00\",\"dateModified\":\"2025-08-06T18:13:48-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado - Serra FM 87,9","description":"O Instituto Federal do Sert\u00e3o Pernambucano (IFSert\u00e3oPE) abre inscri\u00e7\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\u00e9cnicos gratuitos nas modalidades Ensino M\u00e9dio Integrado e Subsequente (p\u00f3s-m\u00e9dio), com ingresso em 2026. As inscri\u00e7\u00f5es seguir\u00e3o at\u00e9 o dia 14 de setembro. No campus Serra Talhada, est\u00e3o sendo ofertados quatro cursos presenciais e gratuitos: Ensino M\u00e9dio Integrado ao T\u00e9cnico em","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#blogposting","name":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado - Serra FM 87,9","headline":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PS-2026.jpeg","width":1024,"height":1024},"datePublished":"2025-08-06T18:13:18-03:00","dateModified":"2025-08-06T18:13:48-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#listItem","name":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#listItem","position":3,"name":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/","name":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado - Serra FM 87,9","description":"O Instituto Federal do Sert\u00e3o Pernambucano (IFSert\u00e3oPE) abre inscri\u00e7\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\u00e9cnicos gratuitos nas modalidades Ensino M\u00e9dio Integrado e Subsequente (p\u00f3s-m\u00e9dio), com ingresso em 2026. As inscri\u00e7\u00f5es seguir\u00e3o at\u00e9 o dia 14 de setembro. No campus Serra Talhada, est\u00e3o sendo ofertados quatro cursos presenciais e gratuitos: Ensino M\u00e9dio Integrado ao T\u00e9cnico em","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PS-2026.jpeg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#mainImage","width":1024,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/#mainImage"},"datePublished":"2025-08-06T18:13:18-03:00","dateModified":"2025-08-06T18:13:48-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado - Serra FM 87,9","twitter:description":"O Instituto Federal do Sert\u00e3o Pernambucano (IFSert\u00e3oPE) abre inscri\u00e7\u00f5es nesta sexta-feira (08), para os processos seletivos de cursos t\u00e9cnicos gratuitos nas modalidades Ensino M\u00e9dio Integrado e Subsequente (p\u00f3s-m\u00e9dio), com ingresso em 2026. As inscri\u00e7\u00f5es seguir\u00e3o at\u00e9 o dia 14 de setembro. No campus Serra Talhada, est\u00e3o sendo ofertados quatro cursos presenciais e gratuitos: Ensino M\u00e9dio Integrado ao T\u00e9cnico em","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PS-2026.jpeg"},"aioseo_meta_data":{"post_id":"23690","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:39:49","updated":"2026-07-21 16:39:49"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tIFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"IFSert\u00e3oPE abre inscri\u00e7\u00f5es para cursos t\u00e9cnicos gratuitos em Serra Talhada e demais cidades do interior do estado","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/ifsertaope-abre-inscricoes-para-cursos-tecnicos-gratuitos-em-serra-talhada-e-demais-cidades-do-interior-do-estado\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/PS-2026.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-6a6","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23690"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23690\/revisions"}],"predecessor-version":[{"id":23692,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23690\/revisions\/23692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23691"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}