{"id":23744,"date":"2025-08-08T08:21:50","date_gmt":"2025-08-08T11:21:50","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23744"},"modified":"2025-08-08T08:21:50","modified_gmt":"2025-08-08T11:21:50","slug":"sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/","title":{"rendered":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos"},"content":{"rendered":"<p>O Governo Federal anunciou, nesta semana, o envio de 2.007 m\u00e9dicos do programa Mais M\u00e9dicos para todo o pa\u00eds. Pernambuco ser\u00e1 contemplado com 110 profissionais, que atuar\u00e3o em mais de um ter\u00e7o dos munic\u00edpios do estado.<\/p>\n<p>No Sert\u00e3o do Moxot\u00f3, sete cidades receber\u00e3o refor\u00e7o na equipe de aten\u00e7\u00e3o b\u00e1sica: Arcoverde (1 m\u00e9dico), Bet\u00e2nia (1), Cust\u00f3dia (1), Ibimirim (2), Inaj\u00e1 (3), Manar\u00ed (2) e Sert\u00e2nia (1).<\/p>\n<p>J\u00e1 no Sert\u00e3o do Paje\u00fa, os munic\u00edpios contemplados nesta etapa s\u00e3o Carna\u00edba (1 m\u00e9dico), Ingazeira (1), Quixaba (1) e S\u00e3o Jos\u00e9 do Egito (1).<\/p>\n<p>O Mais M\u00e9dicos, criado em 2013, tem como objetivo ampliar a presen\u00e7a de profissionais de sa\u00fade em regi\u00f5es com dificuldade de fixa\u00e7\u00e3o de m\u00e9dicos, especialmente no interior e em \u00e1reas vulner\u00e1veis. Segundo o Minist\u00e9rio da Sa\u00fade, os novos profissionais devem come\u00e7ar a atuar nas unidades b\u00e1sicas de sa\u00fade nos pr\u00f3ximos meses, refor\u00e7ando o atendimento \u00e0 popula\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo Federal anunciou, nesta semana, o envio de 2.007 m\u00e9dicos do programa Mais M\u00e9dicos para todo o pa\u00eds. Pernambuco ser\u00e1 contemplado com 110 profissionais, que atuar\u00e3o em mais de um ter\u00e7o dos munic\u00edpios do estado. No Sert\u00e3o do Moxot\u00f3, sete cidades receber\u00e3o refor\u00e7o na equipe de aten\u00e7\u00e3o b\u00e1sica: Arcoverde (1 m\u00e9dico), Bet\u00e2nia (1), Cust\u00f3dia (1), Ibimirim (2), Inaj\u00e1 (3), Manar\u00ed (2) e Sert\u00e2nia (1). J\u00e1 no Sert\u00e3o do Paje\u00fa, os munic\u00edpios contemplados nesta etapa s\u00e3o Carna\u00edba (1 m\u00e9dico), Ingazeira (1), Quixaba (1) e S\u00e3o Jos\u00e9 do Egito (1). O Mais M\u00e9dicos, criado em 2013, tem como objetivo ampliar a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Governo Federal anunciou, nesta semana, o envio de 2.007 m\u00e9dicos do programa Mais M\u00e9dicos para todo o pa\u00eds. Pernambuco ser\u00e1 contemplado com 110 profissionais, que atuar\u00e3o em mais de um ter\u00e7o dos munic\u00edpios do estado. No Sert\u00e3o do Moxot\u00f3, sete cidades receber\u00e3o refor\u00e7o na equipe de aten\u00e7\u00e3o b\u00e1sica: Arcoverde (1 m\u00e9dico), Bet\u00e2nia (1), Cust\u00f3dia\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Governo Federal anunciou, nesta semana, o envio de 2.007 m\u00e9dicos do programa Mais M\u00e9dicos para todo o pa\u00eds. Pernambuco ser\u00e1 contemplado com 110 profissionais, que atuar\u00e3o em mais de um ter\u00e7o dos munic\u00edpios do estado. No Sert\u00e3o do Moxot\u00f3, sete cidades receber\u00e3o refor\u00e7o na equipe de aten\u00e7\u00e3o b\u00e1sica: Arcoverde (1 m\u00e9dico), Bet\u00e2nia (1), Cust\u00f3dia\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-082310.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#blogposting\",\"name\":\"Sert\\u00e3o do Paje\\u00fa receber\\u00e1 novos profissionais do Programa Mais M\\u00e9dicos - Serra FM 87,9\",\"headline\":\"Sert\\u00e3o do Paje\\u00fa receber\\u00e1 novos profissionais do Programa Mais M\\u00e9dicos\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-08-082310.png\",\"width\":308,\"height\":152},\"datePublished\":\"2025-08-08T08:21:50-03:00\",\"dateModified\":\"2025-08-08T08:21:50-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#listItem\",\"name\":\"Sert\\u00e3o do Paje\\u00fa receber\\u00e1 novos profissionais do Programa Mais M\\u00e9dicos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#listItem\",\"position\":3,\"name\":\"Sert\\u00e3o do Paje\\u00fa receber\\u00e1 novos profissionais do Programa Mais M\\u00e9dicos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/\",\"name\":\"Sert\\u00e3o do Paje\\u00fa receber\\u00e1 novos profissionais do Programa Mais M\\u00e9dicos - Serra FM 87,9\",\"description\":\"O Governo Federal anunciou, nesta semana, o envio de 2.007 m\\u00e9dicos do programa Mais M\\u00e9dicos para todo o pa\\u00eds. Pernambuco ser\\u00e1 contemplado com 110 profissionais, que atuar\\u00e3o em mais de um ter\\u00e7o dos munic\\u00edpios do estado. No Sert\\u00e3o do Moxot\\u00f3, sete cidades receber\\u00e3o refor\\u00e7o na equipe de aten\\u00e7\\u00e3o b\\u00e1sica: Arcoverde (1 m\\u00e9dico), Bet\\u00e2nia (1), Cust\\u00f3dia\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-08-082310.png\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#mainImage\",\"width\":308,\"height\":152},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\\\/#mainImage\"},\"datePublished\":\"2025-08-08T08:21:50-03:00\",\"dateModified\":\"2025-08-08T08:21:50-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos - Serra FM 87,9","description":"O Governo Federal anunciou, nesta semana, o envio de 2.007 m\u00e9dicos do programa Mais M\u00e9dicos para todo o pa\u00eds. Pernambuco ser\u00e1 contemplado com 110 profissionais, que atuar\u00e3o em mais de um ter\u00e7o dos munic\u00edpios do estado. No Sert\u00e3o do Moxot\u00f3, sete cidades receber\u00e3o refor\u00e7o na equipe de aten\u00e7\u00e3o b\u00e1sica: Arcoverde (1 m\u00e9dico), Bet\u00e2nia (1), Cust\u00f3dia","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#blogposting","name":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos - Serra FM 87,9","headline":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-082310.png","width":308,"height":152},"datePublished":"2025-08-08T08:21:50-03:00","dateModified":"2025-08-08T08:21:50-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#listItem","name":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#listItem","position":3,"name":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/","name":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos - Serra FM 87,9","description":"O Governo Federal anunciou, nesta semana, o envio de 2.007 m\u00e9dicos do programa Mais M\u00e9dicos para todo o pa\u00eds. Pernambuco ser\u00e1 contemplado com 110 profissionais, que atuar\u00e3o em mais de um ter\u00e7o dos munic\u00edpios do estado. No Sert\u00e3o do Moxot\u00f3, sete cidades receber\u00e3o refor\u00e7o na equipe de aten\u00e7\u00e3o b\u00e1sica: Arcoverde (1 m\u00e9dico), Bet\u00e2nia (1), Cust\u00f3dia","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-082310.png","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#mainImage","width":308,"height":152},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/#mainImage"},"datePublished":"2025-08-08T08:21:50-03:00","dateModified":"2025-08-08T08:21:50-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos - Serra FM 87,9","twitter:description":"O Governo Federal anunciou, nesta semana, o envio de 2.007 m\u00e9dicos do programa Mais M\u00e9dicos para todo o pa\u00eds. Pernambuco ser\u00e1 contemplado com 110 profissionais, que atuar\u00e3o em mais de um ter\u00e7o dos munic\u00edpios do estado. No Sert\u00e3o do Moxot\u00f3, sete cidades receber\u00e3o refor\u00e7o na equipe de aten\u00e7\u00e3o b\u00e1sica: Arcoverde (1 m\u00e9dico), Bet\u00e2nia (1), Cust\u00f3dia","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-082310.png"},"aioseo_meta_data":{"post_id":"23744","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:41:38","updated":"2026-07-21 16:41:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"Sert\u00e3o do Paje\u00fa receber\u00e1 novos profissionais do Programa Mais M\u00e9dicos","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/sertao-do-pajeu-recebera-novos-profissionais-do-programa-mais-medicos\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-082310.png","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-6aY","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23744"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23744\/revisions"}],"predecessor-version":[{"id":23746,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23744\/revisions\/23746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23745"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}