{"id":23756,"date":"2025-08-08T08:58:55","date_gmt":"2025-08-08T11:58:55","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23756"},"modified":"2025-08-08T08:58:55","modified_gmt":"2025-08-08T11:58:55","slug":"projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/","title":{"rendered":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco"},"content":{"rendered":"<p>Um Projeto de Lei Ordin\u00e1ria (PLO) visa proibir a perman\u00eancia de\u00a0animais\u00a0sozinhos no interior de ve\u00edculos automotores em Pernambuco.<\/p>\n<p>O respons\u00e1vel pelo pet que infringir a lei estar\u00e1 sujeito \u00e0 multa de R$ 500\u00a0na primeira ocorr\u00eancia e R$ 1.000\u00a0em casos de reincid\u00eancia.<\/p>\n<p>&#8220;A exposi\u00e7\u00e3o de animais ao confinamento em ve\u00edculos fechados, especialmente sob sol intenso ou em ambientes pouco ventilados, pode causar graves consequ\u00eancias, como estresse t\u00e9rmico, desidrata\u00e7\u00e3o, insola\u00e7\u00e3o, insufici\u00eancia respirat\u00f3ria e, em casos extremos, levar \u00e0 morte por hipertermia ou hipotermia. Apesar de amplamente divulgado, esse tipo de conduta ainda \u00e9 frequentemente registrado em estacionamentos de shoppings, supermercados, vias p\u00fablicas e demais locais com grande circula\u00e7\u00e3o de pessoas&#8221;, diz a justificativa do projeto.<\/p>\n<p>Proposto pelo deputado Romero Albuquerque na Assembleia Legislativa de Pernambuco (Alepe), o PLO 3096\/2025 tem como principal intuito manter a integridade f\u00edsica dos animais.<\/p>\n<p>Publicado na quarta-feira (6), o PLO considera infra\u00e7\u00f5es, especialmente, quando:<\/p>\n<div>\n<p>\u00a0 \u00a0I &#8211; o ve\u00edculo estiver estacionado com as janelas completamente fechadas ou sem ventila\u00e7\u00e3o adequada;<\/p>\n<p>II &#8211; a temperatura interna do ve\u00edculo oferecer risco de hipertermia, insola\u00e7\u00e3o ou hipotermia ao animal; e<\/p>\n<p>III &#8211; o animal permanecer desacompanhado por per\u00edodo superior a 5 (cinco) minutos, salvo em condi\u00e7\u00f5es ambientalmente seguras e sob vigil\u00e2ncia externa.<\/p>\n<p>Segundo a proposi\u00e7\u00e3o, qualquer autoridade p\u00fablica estadual ou municipal pode intervir para proteger a integridade do animal, inclusive atuando para a abertura do ve\u00edculo com o aux\u00edlio da for\u00e7a policial, se necess\u00e1rio.<\/p>\n<p>Um animal resgatado de situa\u00e7\u00f5es do tipo dever\u00e1 ser encaminhado imediatamente para avalia\u00e7\u00e3o por profissional veterin\u00e1rio.<\/p>\n<p>A autoridade competente dever\u00e1 registrar o fato e comunicar aos \u00f3rg\u00e3os de prote\u00e7\u00e3o e defesa animal.<\/p>\n<p>Al\u00e9m disso, \u00e9 poss\u00edvel que o tutor perca temporariamente o direito de guarda do pet, mediante avalia\u00e7\u00e3o do \u00f3rg\u00e3o competente, em caso de maus-tratos ou reincid\u00eancia grave.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um Projeto de Lei Ordin\u00e1ria (PLO) visa proibir a perman\u00eancia de\u00a0animais\u00a0sozinhos no interior de ve\u00edculos automotores em Pernambuco. O respons\u00e1vel pelo pet que infringir a lei estar\u00e1 sujeito \u00e0 multa de R$ 500\u00a0na primeira ocorr\u00eancia e R$ 1.000\u00a0em casos de reincid\u00eancia. &#8220;A exposi\u00e7\u00e3o de animais ao confinamento em ve\u00edculos fechados, especialmente sob sol intenso ou em ambientes pouco ventilados, pode causar graves consequ\u00eancias, como estresse t\u00e9rmico, desidrata\u00e7\u00e3o, insola\u00e7\u00e3o, insufici\u00eancia respirat\u00f3ria e, em casos extremos, levar \u00e0 morte por hipertermia ou hipotermia. Apesar de amplamente divulgado, esse tipo de conduta ainda \u00e9 frequentemente registrado em estacionamentos de shoppings, supermercados, vias p\u00fablicas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Um Projeto de Lei Ordin\u00e1ria (PLO) visa proibir a perman\u00eancia de animais sozinhos no interior de ve\u00edculos automotores em Pernambuco. O respons\u00e1vel pelo pet que infringir a lei estar\u00e1 sujeito \u00e0 multa de R$ 500 na primeira ocorr\u00eancia e R$ 1.000 em casos de reincid\u00eancia. &quot;A exposi\u00e7\u00e3o de animais ao confinamento em ve\u00edculos fechados, especialmente sob sol intenso ou\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Um Projeto de Lei Ordin\u00e1ria (PLO) visa proibir a perman\u00eancia de animais sozinhos no interior de ve\u00edculos automotores em Pernambuco. O respons\u00e1vel pelo pet que infringir a lei estar\u00e1 sujeito \u00e0 multa de R$ 500 na primeira ocorr\u00eancia e R$ 1.000 em casos de reincid\u00eancia. &quot;A exposi\u00e7\u00e3o de animais ao confinamento em ve\u00edculos fechados, especialmente sob sol intenso ou\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-090022.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#blogposting\",\"name\":\"Projeto visa proibir pets desacompanhados no interior de ve\\u00edculos em Pernambuco - Serra FM 87,9\",\"headline\":\"Projeto visa proibir pets desacompanhados no interior de ve\\u00edculos em Pernambuco\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-08-090022.png\",\"width\":255,\"height\":164},\"datePublished\":\"2025-08-08T08:58:55-03:00\",\"dateModified\":\"2025-08-08T08:58:55-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#listItem\",\"name\":\"Projeto visa proibir pets desacompanhados no interior de ve\\u00edculos em Pernambuco\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#listItem\",\"position\":3,\"name\":\"Projeto visa proibir pets desacompanhados no interior de ve\\u00edculos em Pernambuco\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/\",\"name\":\"Projeto visa proibir pets desacompanhados no interior de ve\\u00edculos em Pernambuco - Serra FM 87,9\",\"description\":\"Um Projeto de Lei Ordin\\u00e1ria (PLO) visa proibir a perman\\u00eancia de animais sozinhos no interior de ve\\u00edculos automotores em Pernambuco. O respons\\u00e1vel pelo pet que infringir a lei estar\\u00e1 sujeito \\u00e0 multa de R$ 500 na primeira ocorr\\u00eancia e R$ 1.000 em casos de reincid\\u00eancia. \\\"A exposi\\u00e7\\u00e3o de animais ao confinamento em ve\\u00edculos fechados, especialmente sob sol intenso ou\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Captura-de-tela-2025-08-08-090022.png\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#mainImage\",\"width\":255,\"height\":164},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\\\/#mainImage\"},\"datePublished\":\"2025-08-08T08:58:55-03:00\",\"dateModified\":\"2025-08-08T08:58:55-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco - Serra FM 87,9","description":"Um Projeto de Lei Ordin\u00e1ria (PLO) visa proibir a perman\u00eancia de animais sozinhos no interior de ve\u00edculos automotores em Pernambuco. O respons\u00e1vel pelo pet que infringir a lei estar\u00e1 sujeito \u00e0 multa de R$ 500 na primeira ocorr\u00eancia e R$ 1.000 em casos de reincid\u00eancia. \"A exposi\u00e7\u00e3o de animais ao confinamento em ve\u00edculos fechados, especialmente sob sol intenso ou","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#blogposting","name":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco - Serra FM 87,9","headline":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-090022.png","width":255,"height":164},"datePublished":"2025-08-08T08:58:55-03:00","dateModified":"2025-08-08T08:58:55-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#webpage"},"articleSection":"Not\u00edcias"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#listItem","name":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#listItem","position":3,"name":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/","name":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco - Serra FM 87,9","description":"Um Projeto de Lei Ordin\u00e1ria (PLO) visa proibir a perman\u00eancia de animais sozinhos no interior de ve\u00edculos automotores em Pernambuco. O respons\u00e1vel pelo pet que infringir a lei estar\u00e1 sujeito \u00e0 multa de R$ 500 na primeira ocorr\u00eancia e R$ 1.000 em casos de reincid\u00eancia. \"A exposi\u00e7\u00e3o de animais ao confinamento em ve\u00edculos fechados, especialmente sob sol intenso ou","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-090022.png","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#mainImage","width":255,"height":164},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/#mainImage"},"datePublished":"2025-08-08T08:58:55-03:00","dateModified":"2025-08-08T08:58:55-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco - Serra FM 87,9","twitter:description":"Um Projeto de Lei Ordin\u00e1ria (PLO) visa proibir a perman\u00eancia de animais sozinhos no interior de ve\u00edculos automotores em Pernambuco. O respons\u00e1vel pelo pet que infringir a lei estar\u00e1 sujeito \u00e0 multa de R$ 500 na primeira ocorr\u00eancia e R$ 1.000 em casos de reincid\u00eancia. &quot;A exposi\u00e7\u00e3o de animais ao confinamento em ve\u00edculos fechados, especialmente sob sol intenso ou","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-090022.png"},"aioseo_meta_data":{"post_id":"23756","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 16:41:38","updated":"2026-07-21 16:41:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProjeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Not\u00edcias","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/noticias\/"},{"label":"Projeto visa proibir pets desacompanhados no interior de ve\u00edculos em Pernambuco","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/projeto-visa-proibir-pets-desacompanhados-no-interior-de-veiculos-em-pernambuco\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/08\/Captura-de-tela-2025-08-08-090022.png","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-6ba","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23756"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23756\/revisions"}],"predecessor-version":[{"id":23758,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23756\/revisions\/23758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/23757"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}