{"id":23770,"date":"2025-08-10T21:37:19","date_gmt":"2025-08-11T00:37:19","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=23770"},"modified":"2025-08-10T21:37:19","modified_gmt":"2025-08-11T00:37:19","slug":"duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/","title":{"rendered":"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana"},"content":{"rendered":"<p>A tranquilidade na Avenida Edineia Martins Santana, pr\u00f3xima ao cemit\u00e9rio de Flores, foi interrompida por gritos e agita\u00e7\u00e3o no final da tarde desse s\u00e1bado (9). Duas mulheres se envolveram em uma discuss\u00e3o acalorada, trocando ofensas e acusa\u00e7\u00f5es de \u201croubo\u201d de parceiro.<\/p>\n<p>Durante a briga, uma das mulheres estava armada com uma faca e chegou a amea\u00e7ar matar a rival. A situa\u00e7\u00e3o s\u00f3 n\u00e3o evoluiu para algo mais grave gra\u00e7as \u00e0 interven\u00e7\u00e3o de uma testemunha, que segurou o bra\u00e7o da suspeita at\u00e9 a chegada da Pol\u00edcia Militar.<\/p>\n<p>As duas mulheres foram conduzidas \u00e0 Delegacia, onde a arma branca foi apreendida para as devidas provid\u00eancias legais.<\/p>\n<p><em>Informa\u00e7\u00f5es do Blog Junior Campos<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tranquilidade na Avenida Edineia Martins Santana, pr\u00f3xima ao cemit\u00e9rio de Flores, foi interrompida por gritos e agita\u00e7\u00e3o no final da tarde desse s\u00e1bado (9). Duas mulheres se envolveram em uma discuss\u00e3o acalorada, trocando ofensas e acusa\u00e7\u00f5es de \u201croubo\u201d de parceiro. Durante a briga, uma das mulheres estava armada com uma faca e chegou a amea\u00e7ar matar a rival. A situa\u00e7\u00e3o s\u00f3 n\u00e3o evoluiu para algo mais grave gra\u00e7as \u00e0 interven\u00e7\u00e3o de uma testemunha, que segurou o bra\u00e7o da suspeita at\u00e9 a chegada da Pol\u00edcia Militar. As duas mulheres foram conduzidas \u00e0 Delegacia, onde a arma branca foi apreendida para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-23770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana - Serra FM 87,9<\/title>\n<meta name=\"description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana - Serra FM 87,9\" \/>\n<meta property=\"og:description\" content=\"Serra FM - Todo Mundo Ouve!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Serra FM 87,9\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-11T00:37:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"728\" \/>\n\t<meta property=\"og:image:height\" content=\"405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"serrafm87\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"serrafm87\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/\",\"name\":\"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana - Serra FM 87,9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sirene-noturna43-policia-728x405-1.jpg\",\"datePublished\":\"2025-08-11T00:37:19+00:00\",\"description\":\"Serra FM - Todo Mundo Ouve!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sirene-noturna43-policia-728x405-1.jpg\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sirene-noturna43-policia-728x405-1.jpg\",\"width\":728,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/08\\\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"R\u00e1dio Serra FM 87,9\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"contentUrl\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logoserra-1.png\",\"width\":225,\"height\":225,\"caption\":\"R\u00e1dio Serra FM 87,9\"},\"image\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana - Serra FM 87,9","description":"Serra FM - Todo Mundo Ouve!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/","og_locale":"pt_BR","og_type":"article","og_title":"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana - Serra FM 87,9","og_description":"Serra FM - Todo Mundo Ouve!","og_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/","og_site_name":"Serra FM 87,9","article_published_time":"2025-08-11T00:37:19+00:00","og_image":[{"width":728,"height":405,"url":"http:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","type":"image\/jpeg"}],"author":"serrafm87","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"serrafm87","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/","name":"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana - Serra FM 87,9","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/#primaryimage"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","datePublished":"2025-08-11T00:37:19+00:00","description":"Serra FM - Todo Mundo Ouve!","breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/#primaryimage","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","width":728,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/08\/duas-mulheres-quase-se-travam-na-faca-por-causa-de-homem-no-sertao-do-pajeu-nesse-final-de-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"ListItem","position":2,"name":"Duas mulheres quase se travam na faca por causa de homem, no Sert\u00e3o do Paje\u00fa, nesse final de semana"}]},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serrafm879.com.br\/serrafm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"R\u00e1dio Serra FM 87,9","url":"https:\/\/serrafm879.com.br\/serrafm\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","contentUrl":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2023\/06\/logoserra-1.png","width":225,"height":225,"caption":"R\u00e1dio Serra FM 87,9"},"image":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#\/schema\/logo\/image\/"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2020\/12\/sirene-noturna43-policia-728x405-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-6bo","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=23770"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23770\/revisions"}],"predecessor-version":[{"id":23771,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/23770\/revisions\/23771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/4096"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=23770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=23770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=23770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}