{"id":24640,"date":"2025-10-20T12:35:19","date_gmt":"2025-10-20T15:35:19","guid":{"rendered":"https:\/\/serrafm879.com.br\/serrafm\/?p=24640"},"modified":"2025-10-20T12:35:19","modified_gmt":"2025-10-20T15:35:19","slug":"expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada","status":"publish","type":"post","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/","title":{"rendered":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada"},"content":{"rendered":"<p>A etapa nacional da Expoberro 2025 encerrou sua edi\u00e7\u00e3o neste domingo (19) com resultados hist\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\u00f5es em neg\u00f3cios, somando as vendas do leil\u00e3o, negocia\u00e7\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi a maior edi\u00e7\u00e3o da hist\u00f3ria da feira, que se consolida como uma das principais vitrines da caprinovinocultura no Brasil.<\/p>\n<p>\u201cA Expoberro \u00e9 um orgulho para o nosso munic\u00edpio e para todo o Sert\u00e3o. O evento movimenta a economia local, fortalece o agroneg\u00f3cio e mostra o potencial da nossa gente. \u00c9 o resultado de um trabalho coletivo, do apoio dos parceiros e do empenho dos criadores, que acreditam e investem nesse setor t\u00e3o importante para a nossa regi\u00e3o\u201d, destacou a prefeita de Serra Talhada, M\u00e1rcia Conrado.<\/p>\n<p>A feira contou com participa\u00e7\u00e3o de criadores de 13 estados brasileiros, representando todas as cinco regi\u00f5es do pa\u00eds e 63 munic\u00edpios. Foram expostos 1.182 animais, com destaque para as ra\u00e7as Dorper e White Dorper, e R$ 70 mil em premia\u00e7\u00f5es distribu\u00eddos aos vencedores. No leil\u00e3o, foram registradas vendas superiores a R$ 3,1 milh\u00f5es, enquanto as negocia\u00e7\u00f5es diretas nas baias somaram cerca de R$ 3 milh\u00f5es. J\u00e1 o Banco do Nordeste assinou contratos que ultrapassaram os R$ 4 milh\u00f5es em investimentos durante o evento.<\/p>\n<p>Os criadores de Serra Talhada tamb\u00e9m se destacaram nas competi\u00e7\u00f5es: um dos animais do munic\u00edpio conquistou o 2\u00b0 e outro o 9\u00b0 lugar no campeonato nacional, que teve julgamentos realizados por tr\u00eas ju\u00edzes africanos credenciados. A Expoberro contou ainda com apoio do Sebrae, que aportou R$ 380 mil, e do Banco do Nordeste, com R$ 100 mil, al\u00e9m da parceria com o Sesc, que cedeu o espa\u00e7o para realiza\u00e7\u00e3o do evento. No total, o investimento da Prefeitura de Serra Talhada foi de cerca de R$ 500 mil.<\/p>\n<p>\u201cCada edi\u00e7\u00e3o da Expoberro reafirma o papel de Serra Talhada como refer\u00eancia nacional no fortalecimento da caprinovinocultura. Mais do que n\u00fameros, o que celebramos \u00e9 o impacto social e econ\u00f4mico que a feira gera para o nosso povo e para o futuro do Sert\u00e3o\u201d, concluiu M\u00e1rcia Conrado.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A etapa nacional da Expoberro 2025 encerrou sua edi\u00e7\u00e3o neste domingo (19) com resultados hist\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\u00f5es em neg\u00f3cios, somando as vendas do leil\u00e3o, negocia\u00e7\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi a maior edi\u00e7\u00e3o da hist\u00f3ria da feira, que se consolida como uma das principais vitrines da caprinovinocultura no Brasil. \u201cA Expoberro \u00e9 um orgulho para o nosso munic\u00edpio e para todo o Sert\u00e3o. O evento movimenta a economia local, fortalece o agroneg\u00f3cio e mostra o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[290],"tags":[],"class_list":["post-24640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-serra-talhada"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"A etapa nacional da Expoberro 2025 encerrou sua edi\u00e7\u00e3o neste domingo (19) com resultados hist\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\u00f5es em neg\u00f3cios, somando as vendas do leil\u00e3o, negocia\u00e7\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"serrafm87\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada - Serra FM 87,9\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A etapa nacional da Expoberro 2025 encerrou sua edi\u00e7\u00e3o neste domingo (19) com resultados hist\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\u00f5es em neg\u00f3cios, somando as vendas do leil\u00e3o, negocia\u00e7\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/10\/138a93db-db97-4fd2-a0fb-c1cc4e18a54e-768x492-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#blogposting\",\"name\":\"Expoberro 2025 movimenta mais de R$ 11 milh\\u00f5es e bate recordes em Serra Talhada - Serra FM 87,9\",\"headline\":\"Expoberro 2025 movimenta mais de R$ 11 milh\\u00f5es e bate recordes em Serra Talhada\",\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/138a93db-db97-4fd2-a0fb-c1cc4e18a54e-768x492-1.jpg\",\"width\":768,\"height\":492},\"datePublished\":\"2025-10-20T12:35:19-03:00\",\"dateModified\":\"2025-10-20T12:35:19-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#webpage\"},\"articleSection\":\"Serra Talhada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/serra-talhada\\\/#listItem\",\"name\":\"Serra Talhada\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/serra-talhada\\\/#listItem\",\"position\":2,\"name\":\"Serra Talhada\",\"item\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/serra-talhada\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#listItem\",\"name\":\"Expoberro 2025 movimenta mais de R$ 11 milh\\u00f5es e bate recordes em Serra Talhada\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#listItem\",\"position\":3,\"name\":\"Expoberro 2025 movimenta mais de R$ 11 milh\\u00f5es e bate recordes em Serra Talhada\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/categoria\\\/serra-talhada\\\/#listItem\",\"name\":\"Serra Talhada\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/\",\"name\":\"serrafm87\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"serrafm87\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#webpage\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/\",\"name\":\"Expoberro 2025 movimenta mais de R$ 11 milh\\u00f5es e bate recordes em Serra Talhada - Serra FM 87,9\",\"description\":\"A etapa nacional da Expoberro 2025 encerrou sua edi\\u00e7\\u00e3o neste domingo (19) com resultados hist\\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\\u00f5es em neg\\u00f3cios, somando as vendas do leil\\u00e3o, negocia\\u00e7\\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/author\\\/serrafm87\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/138a93db-db97-4fd2-a0fb-c1cc4e18a54e-768x492-1.jpg\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#mainImage\",\"width\":768,\"height\":492},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/2025\\\/10\\\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\\\/#mainImage\"},\"datePublished\":\"2025-10-20T12:35:19-03:00\",\"dateModified\":\"2025-10-20T12:35:19-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#website\",\"url\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/\",\"name\":\"Serra FM 87,9\",\"description\":\"O seu novo amor!\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/serrafm879.com.br\\\/serrafm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada - Serra FM 87,9","description":"A etapa nacional da Expoberro 2025 encerrou sua edi\u00e7\u00e3o neste domingo (19) com resultados hist\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\u00f5es em neg\u00f3cios, somando as vendas do leil\u00e3o, negocia\u00e7\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi","canonical_url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#blogposting","name":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada - Serra FM 87,9","headline":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada","author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/10\/138a93db-db97-4fd2-a0fb-c1cc4e18a54e-768x492-1.jpg","width":768,"height":492},"datePublished":"2025-10-20T12:35:19-03:00","dateModified":"2025-10-20T12:35:19-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#webpage"},"isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#webpage"},"articleSection":"Serra Talhada"},{"@type":"BreadcrumbList","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","position":1,"name":"Home","item":"https:\/\/serrafm879.com.br\/serrafm","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/serra-talhada\/#listItem","name":"Serra Talhada"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/serra-talhada\/#listItem","position":2,"name":"Serra Talhada","item":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/serra-talhada\/","nextItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#listItem","name":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada"},"previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#listItem","position":3,"name":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada","previousItem":{"@type":"ListItem","@id":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/serra-talhada\/#listItem","name":"Serra Talhada"}}]},{"@type":"Organization","@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization","name":"Serra FM 87,9","description":"O seu novo amor!","url":"https:\/\/serrafm879.com.br\/serrafm\/"},{"@type":"Person","@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author","url":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/","name":"serrafm87","image":{"@type":"ImageObject","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a743233f1112d34f48bb3dc9559b76eb930bab8b27175856cba6362608736235?s=96&d=mm&r=g","width":96,"height":96,"caption":"serrafm87"}},{"@type":"WebPage","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#webpage","url":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/","name":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada - Serra FM 87,9","description":"A etapa nacional da Expoberro 2025 encerrou sua edi\u00e7\u00e3o neste domingo (19) com resultados hist\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\u00f5es em neg\u00f3cios, somando as vendas do leil\u00e3o, negocia\u00e7\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#website"},"breadcrumb":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#breadcrumblist"},"author":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"creator":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/author\/serrafm87\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/10\/138a93db-db97-4fd2-a0fb-c1cc4e18a54e-768x492-1.jpg","@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#mainImage","width":768,"height":492},"primaryImageOfPage":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/#mainImage"},"datePublished":"2025-10-20T12:35:19-03:00","dateModified":"2025-10-20T12:35:19-03:00"},{"@type":"WebSite","@id":"https:\/\/serrafm879.com.br\/serrafm\/#website","url":"https:\/\/serrafm879.com.br\/serrafm\/","name":"Serra FM 87,9","description":"O seu novo amor!","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/serrafm879.com.br\/serrafm\/#organization"}}]},"twitter:card":"summary_large_image","twitter:title":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada - Serra FM 87,9","twitter:description":"A etapa nacional da Expoberro 2025 encerrou sua edi\u00e7\u00e3o neste domingo (19) com resultados hist\u00f3ricos. O evento, realizado em Serra Talhada, movimentou mais de R$ 11 milh\u00f5es em neg\u00f3cios, somando as vendas do leil\u00e3o, negocia\u00e7\u00f5es diretas entre produtores nas baias e contratos assinados com o Banco do Nordeste. De acordo com os organizadores, esta foi","twitter:image":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/10\/138a93db-db97-4fd2-a0fb-c1cc4e18a54e-768x492-1.jpg"},"aioseo_meta_data":{"post_id":"24640","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-07-21 17:30:28","updated":"2026-07-21 17:30:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/serrafm879.com.br\/serrafm\/categoria\/serra-talhada\/\" title=\"Serra Talhada\">Serra Talhada<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tExpoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/serrafm879.com.br\/serrafm"},{"label":"Serra Talhada","link":"https:\/\/serrafm879.com.br\/serrafm\/categoria\/serra-talhada\/"},{"label":"Expoberro 2025 movimenta mais de R$ 11 milh\u00f5es e bate recordes em Serra Talhada","link":"https:\/\/serrafm879.com.br\/serrafm\/2025\/10\/expoberro-2025-movimenta-mais-de-r-11-milhoes-e-bate-recordes-em-serra-talhada\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/serrafm879.com.br\/serrafm\/wp-content\/uploads\/2025\/10\/138a93db-db97-4fd2-a0fb-c1cc4e18a54e-768x492-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7HyXg-6pq","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/24640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/comments?post=24640"}],"version-history":[{"count":1,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/24640\/revisions"}],"predecessor-version":[{"id":24642,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/posts\/24640\/revisions\/24642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media\/24641"}],"wp:attachment":[{"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/media?parent=24640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/categories?post=24640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serrafm879.com.br\/serrafm\/wp-json\/wp\/v2\/tags?post=24640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}